{"id":842,"count":25,"description":"","link":"https:\/\/filles-de-la-charite.org\/en\/category\/international\/","name":"International","slug":"international","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>International archivos - Filles de la Charit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filles-de-la-charite.org\/en\/category\/international\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"International archivos - Filles de la Charit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filles-de-la-charite.org\/en\/category\/international\/\" \/>\n<meta property=\"og:site_name\" content=\"Filles de la Charit\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/en\\\/category\\\/international\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/en\\\/category\\\/international\\\/\",\"name\":\"International archivos - Filles de la Charit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/en\\\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/en\\\/\",\"name\":\"Hijas de la Caridad\",\"description\":\"El amor de Jes\u00fas nos urge a cuidar la vida de los m\u00e1s necesitados\",\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filles-de-la-charite.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/en\\\/#organization\",\"name\":\"Hijas de la Caridad\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"width\":1417,\"height\":1417,\"caption\":\"Hijas de la Caridad\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"International archivos - Filles de la Charit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filles-de-la-charite.org\/en\/category\/international\/","og_locale":"en_US","og_type":"article","og_title":"International archivos - Filles de la Charit\u00e9","og_url":"https:\/\/filles-de-la-charite.org\/en\/category\/international\/","og_site_name":"Filles de la Charit\u00e9","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/filles-de-la-charite.org\/en\/category\/international\/","url":"https:\/\/filles-de-la-charite.org\/en\/category\/international\/","name":"International archivos - Filles de la Charit\u00e9","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/en\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/filles-de-la-charite.org\/en\/#website","url":"https:\/\/filles-de-la-charite.org\/en\/","name":"Hijas de la Caridad","description":"El amor de Jes\u00fas nos urge a cuidar la vida de los m\u00e1s necesitados","publisher":{"@id":"https:\/\/filles-de-la-charite.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filles-de-la-charite.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/filles-de-la-charite.org\/en\/#organization","name":"Hijas de la Caridad","url":"https:\/\/filles-de-la-charite.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/filles-de-la-charite.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","width":1417,"height":1417,"caption":"Hijas de la Caridad"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/filles-de-la-charite.org\/en\/wp-json\/wp\/v2\/categories\/842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filles-de-la-charite.org\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/filles-de-la-charite.org\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/filles-de-la-charite.org\/en\/wp-json\/wp\/v2\/posts?categories=842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}