{"id":22654,"date":"2022-07-31T22:00:00","date_gmt":"2022-07-31T20:00:00","guid":{"rendered":"https:\/\/hijascaridad.sjdigitaldemo.ovh\/triple-benediction-en-juin\/"},"modified":"2026-05-11T13:29:49","modified_gmt":"2026-05-11T11:29:49","slug":"triple-benediction-en-juin","status":"publish","type":"post","link":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/","title":{"rendered":"Triple b\u00e9n\u00e9diction en juin"},"content":{"rendered":"\n<p>La Province Sainte Louise de Marillac \u2013 Asie attendait avec joie le mois de juin en anticipant d'abondantes b\u00e9n\u00e9dictions, dont trois aux \u00ab couleurs arc-en-ciel \u00bb.<\/p>\n\n\n\n<p>Le 31 mai a inaugur\u00e9 le mois de juin avec la d\u00e9signation de Sr. Maria Ana Rosario G. EVIDENTE comme Visitatrice pour 3 autres ann\u00e9es. Au milieu de l'incertitude politique, \u00e9conomique et sociale et du d\u00e9sespoir apparent face aux \u00e9v\u00e9nements mondiaux, cela a apport\u00e9 un espoir incomparable et un sentiment de continuit\u00e9 et d'engagement pour la Province<strong>.<\/strong><\/p>\n\n\n\n<p>Le 4 juin marque le 6e anniversaire de la Province apr\u00e8s sa reconfiguration : une Province, neuf pays. Alors que nous faisions monter notre action de gr\u00e2ces pour l'amour et la mis\u00e9ricorde de Dieu, nous l'avons \u00e9galement lou\u00e9 pour nous avoir envoy\u00e9 un nouveau directeur provincial, en la personne du P. G\u00e9rard VIBAR, CM.<\/p>\n\n\n\n<p>Le 21 juin, retenant le souffle et priant, apr\u00e8s l'annulation du vol initial, les S\u0153urs \u00e9taient dans le hall de la Maison Provinciale aux Philippines, alors que nous accueillions vers minuit Sr. Fran\u00e7oise PETIT, Sup\u00e9rieure G\u00e9n\u00e9rale. Des S\u0153urs repr\u00e9sentant celles du Japon, de Cor\u00e9e du Sud, de Tha\u00eflande, du Laos, du Cambodge, de Papouasie-Nouvelle-Guin\u00e9e, de Ta\u00efwan, de Chine et des diff\u00e9rentes r\u00e9gions des Philippines se sont jointes \u00e0 S\u0153ur Fran\u00e7oise pour offrir un bouquet de fleurs \u00e0 la Sainte Vierge et chanter Son Magnificat !<\/p>\n\n\n\n<figure class=\"wp-block-gallery alignwide columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.filles-de-la-charite.org\/wp-content\/uploads\/news\/August 2022\/Asia\/Junes-Triple-Blessing-Photo-1.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Junes-Triple-Blessing-Photo-1-1024x461-1.jpg\" alt=\"\" data-id=\"70930\" data-full-url=\"https:\/\/www.filles-de-la-charite.org\/wp-content\/uploads\/news\/August 2022\/Asia\/Junes-Triple-Blessing-Photo-1.jpg\" data-link=\"https:\/\/www.filles-de-la-charite.org\/junes-triple-blessing-photo-1\/\" class=\"wp-image-70930\"\/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.filles-de-la-charite.org\/wp-content\/uploads\/news\/August 2022\/Asia\/Junes-Triple-Blessing-Photo-1a-scaled.jpg\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Junes-Triple-Blessing-Photo-1a-1024x576-1.jpg\" alt=\"\" data-id=\"70929\" data-full-url=\"https:\/\/www.filles-de-la-charite.org\/wp-content\/uploads\/news\/August 2022\/Asia\/Junes-Triple-Blessing-Photo-1a-scaled.jpg\" data-link=\"https:\/\/www.filles-de-la-charite.org\/junes-triple-blessing-photo-1a\/\" class=\"wp-image-70929\"\/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/draft.jpg\" alt=\"\" class=\"wp-image-70951\"\/><\/figure><\/div>\n\n\n\n<p>Sr. Fran\u00e7oise n'a pu visiter que quelques Communaut\u00e9s et leur mission aux Philippines ; deux m\u00e9morables ont \u00e9t\u00e9 le Village de la Famille Vincentienne d'Anislag et le Village \u00ab Ati \u00bb.<\/p>\n\n\n\n<p>Anislag \u00e9tait un projet port\u00e9 par les Filles de la Charit\u00e9 en collaboration avec la Soci\u00e9t\u00e9 de Saint-Vincent de Paul, les autres membres de la Famille Vincentienne de diverses mani\u00e8res, et l'Association des Sup\u00e9rieurs Majeurs des Religieux aux Philippines, qui visait \u00e0 construire des maisons pour 330 familles qui ont perdu des \u00eatres chers, des maisons et des fermes lors du typhon d\u00e9vastateur de 2006. Aujourd'hui, c'est une communaut\u00e9 confessionnelle autonome.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Junes-Triple-Blessing-Photo-2a-1024x576-1.jpg\" alt=\"\" class=\"wp-image-70933\"\/><\/figure><\/div>\n\n\n\n<p>Le village \"Ati\" est une terre ancestrale profond\u00e9ment disput\u00e9e et durement gagn\u00e9e par le peuple autochtone appel\u00e9 Ati. Trois Filles de la Charit\u00e9 continuent de vivre dans ce village avec les Ati, luttant avec eux alors qu'elles revendiquent ce qui leur appartient de droit : la terre, le revenu et la vie.<\/p>\n\n\n\n<p>Sr Fran\u00e7oise a \u00e9galement \u00e9t\u00e9 t\u00e9moin de deux c\u00e9l\u00e9brations : le jubil\u00e9 d'argent de 6 Filles de la Charit\u00e9 et le passage \u00e0 la vie \u00e9ternelle de Sr Francisca SANCHEZ.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Photo-3-copia-1024x645-1.jpg\" alt=\"\" class=\"wp-image-70952\"\/><\/figure><\/div>\n\n\n\n<p>Sr. Fran\u00e7oise a quitt\u00e9 les Philippines le 28 juin et s'est envol\u00e9e pour la Cor\u00e9e du Sud o\u00f9 elle a visit\u00e9 le Bono Social Service Center dont les principaux services comprennent l'accueil de jour pour les personnes \u00e2g\u00e9es (alimentation et activit\u00e9s r\u00e9cr\u00e9atives) ainsi que l'accompagnement des familles migrantes qui vise \u00e0 faciliter leur insertion dans la communaut\u00e9 cor\u00e9enne (activit\u00e9s socio-culturelles, cuisine et \u00e9tudes de langues). L\u2019accueil Sainte Louise est un foyer pour femmes et enfants victimes de violences de la part de maris cor\u00e9ens. Le Foyer, en collaboration avec le gouvernement, assure un accompagnement psychologique, culturel, sanitaire et juridique. La derni\u00e8re visite a \u00e9t\u00e9 \u00e0 la Maison Saint Vincent, une institution pour personnes \u00e2g\u00e9es ; appartenant aux Filles de la Charit\u00e9, ayant \u00e9t\u00e9 mise aux normes gouvernementales, elle b\u00e9n\u00e9ficie du soutien du gouvernement.<\/p>\n\n\n\n<p>Pr. L'hom\u00e9lie de Gerardo sur la solennit\u00e9 de Saint Jean-Baptiste peut tr\u00e8s bien r\u00e9sumer ce que la pr\u00e9sence de Sr Fran\u00e7oise signifiait pour la Province : <em>\u00ab S\u0153ur Fran\u00e7oise, veuillez pardonner mon audace, mais permettez-moi de dire ceci \u00e0 nos S\u0153urs de la Province Sainte Louise de Marillac-Asie : ces jours-ci, un ange du Seigneur vous visite (\u2026). Elle vient avec un message de Dieu. (\u2026) nous sommes vraiment remplis de joie et d'all\u00e9gresse lors de votre visite et nous attendrons plus de votre message pour nous, du message de Dieu pour nous. \u00bb<\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"June&#039;s Triple Blessing: The Visit\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/XPKOv769900?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":16998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"categories":[683],"tags":[],"class_list":["post-22654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sainte-louise-usa-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Triple b\u00e9n\u00e9diction en juin - Filles de la Charit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Triple b\u00e9n\u00e9diction en juin - Filles de la Charit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/\" \/>\n<meta property=\"og:site_name\" content=\"Filles de la Charit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-31T20:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T11:29:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/thumbnail-The-Visit-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/triple-benediction-en-juin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/triple-benediction-en-juin\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#\\\/schema\\\/person\\\/427567b2eccfc2dd7d206da186a1f438\"},\"headline\":\"Triple b\u00e9n\u00e9diction en juin\",\"datePublished\":\"2022-07-31T20:00:00+00:00\",\"dateModified\":\"2026-05-11T11:29:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/triple-benediction-en-juin\\\/\"},\"wordCount\":693,\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/triple-benediction-en-juin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/thumbnail-The-Visit-scaled-1.jpg\",\"articleSection\":[\"Sainte Louise - USA\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/triple-benediction-en-juin\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/triple-benediction-en-juin\\\/\",\"name\":\"Triple b\u00e9n\u00e9diction en juin - Filles de la Charit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/triple-benediction-en-juin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/triple-benediction-en-juin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/thumbnail-The-Visit-scaled-1.jpg\",\"datePublished\":\"2022-07-31T20:00:00+00:00\",\"dateModified\":\"2026-05-11T11:29:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/triple-benediction-en-juin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/triple-benediction-en-juin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/triple-benediction-en-juin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/thumbnail-The-Visit-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/thumbnail-The-Visit-scaled-1.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/triple-benediction-en-juin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Indon\u00e9sie\",\"item\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/category\\\/indonesie\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Triple b\u00e9n\u00e9diction en juin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/\",\"name\":\"Hijas de la Caridad\",\"description\":\"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies\",\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#organization\",\"name\":\"Hijas de la Caridad\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"width\":1417,\"height\":1417,\"caption\":\"Hijas de la Caridad\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#\\\/schema\\\/person\\\/427567b2eccfc2dd7d206da186a1f438\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/filles-de-la-charite.org\"],\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/author\\\/caridad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Triple b\u00e9n\u00e9diction en juin - Filles de la Charit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/","og_locale":"fr_FR","og_type":"article","og_title":"Triple b\u00e9n\u00e9diction en juin - Filles de la Charit\u00e9","og_url":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/","og_site_name":"Filles de la Charit\u00e9","article_published_time":"2022-07-31T20:00:00+00:00","article_modified_time":"2026-05-11T11:29:49+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/thumbnail-The-Visit-scaled-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/#article","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/"},"author":{"name":"admin","@id":"https:\/\/filles-de-la-charite.org\/fr\/#\/schema\/person\/427567b2eccfc2dd7d206da186a1f438"},"headline":"Triple b\u00e9n\u00e9diction en juin","datePublished":"2022-07-31T20:00:00+00:00","dateModified":"2026-05-11T11:29:49+00:00","mainEntityOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/"},"wordCount":693,"publisher":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/#organization"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/thumbnail-The-Visit-scaled-1.jpg","articleSection":["Sainte Louise - USA"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/","url":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/","name":"Triple b\u00e9n\u00e9diction en juin - Filles de la Charit\u00e9","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/#primaryimage"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/thumbnail-The-Visit-scaled-1.jpg","datePublished":"2022-07-31T20:00:00+00:00","dateModified":"2026-05-11T11:29:49+00:00","breadcrumb":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/#primaryimage","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/thumbnail-The-Visit-scaled-1.jpg","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/thumbnail-The-Visit-scaled-1.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/filles-de-la-charite.org\/fr\/triple-benediction-en-juin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Indon\u00e9sie","item":"https:\/\/filles-de-la-charite.org\/fr\/category\/indonesie\/"},{"@type":"ListItem","position":2,"name":"Triple b\u00e9n\u00e9diction en juin"}]},{"@type":"WebSite","@id":"https:\/\/filles-de-la-charite.org\/fr\/#website","url":"https:\/\/filles-de-la-charite.org\/fr\/","name":"Hijas de la Caridad","description":"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies","publisher":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filles-de-la-charite.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/filles-de-la-charite.org\/fr\/#organization","name":"Hijas de la Caridad","url":"https:\/\/filles-de-la-charite.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/filles-de-la-charite.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","width":1417,"height":1417,"caption":"Hijas de la Caridad"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/filles-de-la-charite.org\/fr\/#\/schema\/person\/427567b2eccfc2dd7d206da186a1f438","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/filles-de-la-charite.org"],"url":"https:\/\/filles-de-la-charite.org\/fr\/author\/caridad\/"}]}},"_links":{"self":[{"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/posts\/22654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/comments?post=22654"}],"version-history":[{"count":2,"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/posts\/22654\/revisions"}],"predecessor-version":[{"id":50692,"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/posts\/22654\/revisions\/50692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/media\/16998"}],"wp:attachment":[{"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/media?parent=22654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/categories?post=22654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/tags?post=22654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}