{"id":45528,"date":"2025-08-18T00:00:00","date_gmt":"2025-08-17T22:00:00","guid":{"rendered":"https:\/\/filles-de-la-charite.org\/?post_type=rincon-oracion&#038;p=45528"},"modified":"2025-08-18T11:19:51","modified_gmt":"2025-08-18T09:19:51","slug":"marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr","status":"publish","type":"rincon-oracion","link":"https:\/\/filles-de-la-charite.org\/fr\/rincon-oracion\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\/","title":{"rendered":"Marie une Femme Unique, lettre de S\u0153ur Fran\u00e7oise Petit, Sup\u00e9rieure g\u00e9n\u00e9rale, 15 ao\u00fbt 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Chaque ann\u00e9e, en ce jour de l\u2019Assomption, nous c\u00e9l\u00e9brons Marie, celle qui nous accompagne et \u00e0 qui, avec tout le peuple de Dieu, nous demandons d\u2019interc\u00e9der pour nous. Elle est entr\u00e9e dans la gloire, celle que nous partagerons toutes un jour. Que cette f\u00eate de l\u2019Assomption nous aide \u00e0 poursuivre notre chemin de foi et d\u2019humanit\u00e9, que le t\u00e9moignage de Marie nous entra\u00eene \u00e0 une fr\u00e9quentation plus intense de la Parole de Dieu, que nous regardions Marie comme M\u00e8re de J\u00e9sus, M\u00e8re du Christ, disciple avec les disciples. (Lettre de S\u0153ur Fran\u00e7oise Petit, Sup\u00e9rieure g\u00e9n\u00e9rale, 15 ao\u00fbt 2025)<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Marie une Femme Unique, Lettre de S\u0153ur Fran\u00e7oise Petit, Superiores General, 15 ao\u00fbt 2025 FR\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/etwtQ6WDLWU?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"featured_media":45505,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"class_list":["post-45528","rincon-oracion","type-rincon-oracion","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marie une Femme Unique, lettre de S\u0153ur Fran\u00e7oise Petit, Sup\u00e9rieure g\u00e9n\u00e9rale, 15 ao\u00fbt 2025 - Filles de la Charit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filles-de-la-charite.org\/fr\/rincon-oracion\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marie une Femme Unique, lettre de S\u0153ur Fran\u00e7oise Petit, Sup\u00e9rieure g\u00e9n\u00e9rale, 15 ao\u00fbt 2025 - Filles de la Charit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Chaque ann\u00e9e, en ce jour de l\u2019Assomption, nous c\u00e9l\u00e9brons Marie, celle qui nous accompagne et \u00e0 qui, avec tout le peuple de Dieu, nous demandons d\u2019interc\u00e9der pour nous. Elle est entr\u00e9e dans la gloire, celle que nous partagerons toutes un jour. Que cette f\u00eate de l\u2019Assomption nous aide \u00e0 poursuivre notre chemin de foi et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filles-de-la-charite.org\/fr\/rincon-oracion\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Filles de la Charit\u00e9\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-18T09:19:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/08\/FR-Mary-Thumbnail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/rincon-oracion\\\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/rincon-oracion\\\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\\\/\",\"name\":\"Marie une Femme Unique, lettre de S\u0153ur Fran\u00e7oise Petit, Sup\u00e9rieure g\u00e9n\u00e9rale, 15 ao\u00fbt 2025 - Filles de la Charit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/rincon-oracion\\\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/rincon-oracion\\\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/FR-Mary-Thumbnail.jpg\",\"datePublished\":\"2025-08-17T22:00:00+00:00\",\"dateModified\":\"2025-08-18T09:19:51+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/rincon-oracion\\\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/rincon-oracion\\\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/FR-Mary-Thumbnail.jpg\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/FR-Mary-Thumbnail.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/\",\"name\":\"Hijas de la Caridad\",\"description\":\"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies\",\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#organization\",\"name\":\"Hijas de la Caridad\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"width\":1417,\"height\":1417,\"caption\":\"Hijas de la Caridad\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marie une Femme Unique, lettre de S\u0153ur Fran\u00e7oise Petit, Sup\u00e9rieure g\u00e9n\u00e9rale, 15 ao\u00fbt 2025 - Filles de la Charit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filles-de-la-charite.org\/fr\/rincon-oracion\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Marie une Femme Unique, lettre de S\u0153ur Fran\u00e7oise Petit, Sup\u00e9rieure g\u00e9n\u00e9rale, 15 ao\u00fbt 2025 - Filles de la Charit\u00e9","og_description":"Chaque ann\u00e9e, en ce jour de l\u2019Assomption, nous c\u00e9l\u00e9brons Marie, celle qui nous accompagne et \u00e0 qui, avec tout le peuple de Dieu, nous demandons d\u2019interc\u00e9der pour nous. Elle est entr\u00e9e dans la gloire, celle que nous partagerons toutes un jour. Que cette f\u00eate de l\u2019Assomption nous aide \u00e0 poursuivre notre chemin de foi et [&hellip;]","og_url":"https:\/\/filles-de-la-charite.org\/fr\/rincon-oracion\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\/","og_site_name":"Filles de la Charit\u00e9","article_modified_time":"2025-08-18T09:19:51+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/08\/FR-Mary-Thumbnail.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/filles-de-la-charite.org\/fr\/rincon-oracion\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\/","url":"https:\/\/filles-de-la-charite.org\/fr\/rincon-oracion\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\/","name":"Marie une Femme Unique, lettre de S\u0153ur Fran\u00e7oise Petit, Sup\u00e9rieure g\u00e9n\u00e9rale, 15 ao\u00fbt 2025 - Filles de la Charit\u00e9","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/rincon-oracion\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\/#primaryimage"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/rincon-oracion\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/08\/FR-Mary-Thumbnail.jpg","datePublished":"2025-08-17T22:00:00+00:00","dateModified":"2025-08-18T09:19:51+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filles-de-la-charite.org\/fr\/rincon-oracion\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/filles-de-la-charite.org\/fr\/rincon-oracion\/marie-une-femme-unique-lettre-de-soeur-francoise-petit-superiores-general-15-aout-2025-fr\/#primaryimage","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/08\/FR-Mary-Thumbnail.jpg","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/08\/FR-Mary-Thumbnail.jpg","width":1280,"height":720},{"@type":"WebSite","@id":"https:\/\/filles-de-la-charite.org\/fr\/#website","url":"https:\/\/filles-de-la-charite.org\/fr\/","name":"Hijas de la Caridad","description":"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies","publisher":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filles-de-la-charite.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/filles-de-la-charite.org\/fr\/#organization","name":"Hijas de la Caridad","url":"https:\/\/filles-de-la-charite.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/filles-de-la-charite.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","width":1417,"height":1417,"caption":"Hijas de la Caridad"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/rincon-oracion\/45528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/rincon-oracion"}],"about":[{"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/types\/rincon-oracion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/media\/45505"}],"wp:attachment":[{"href":"https:\/\/filles-de-la-charite.org\/fr\/wp-json\/wp\/v2\/media?parent=45528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}