{"id":32251,"date":"2024-03-02T12:55:23","date_gmt":"2024-03-02T11:55:23","guid":{"rendered":"https:\/\/hijascaridad.sjdigitaldemo.ovh\/familia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/"},"modified":"2024-03-12T18:18:13","modified_gmt":"2024-03-12T17:18:13","slug":"beato-louis-joseph-francois-c-m-y-companeros-martires","status":"publish","type":"familia","link":"https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/","title":{"rendered":"Beati Luigi Giuseppe Fran\u00e7ois, C.M., e i compagni martiri"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Chiesa e la Congregazione onorano insieme i martiri della Rivoluzione Francese. A Parigi, il 3 settembre 1792, ci fu un massacro nel seminario di San Firmino, prima denominato Collegio \u201cdes Bons Enfants\u201d, che era stato acquistato da San Vincenzo de Paoli nel 1624. Questo seminario, trasformato in prigione nel 1789, divenne il quarto luogo di esecuzione capitale a Parigi. Settantadue vittime subirono il martirio. Tra questi:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LUIGI GIUSEPPE FRAN\u00c7OIS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nato il 3 febbraio 1751 a Busigny, nel Nord, fu ordinato sacerdote nel 1773 ed ammesso nella Congregazione della Missione il 4 ottobre 1776. Fu \u201cmissionario\u201d nella formazione dei preti, prima nel seminario di Troyes, poi a Parigi nel seminario di San Firmino dove divenne superiore nel 1788.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nonostante i tempi fossero difficile, vigil\u00f2 affinch\u00e9 nel seminario fosse vissuta una vita regolare. Scrisse diversi opuscoli contro la Costituzione civile del clero, tra cui \u00abApologia\u00bb. Mentre la persecuzione era gi\u00e0 in atto, apr\u00ec le porte del seminario di Sa a Parigi a pi\u00f9 di novanta sacerdoti e religiosi. Quando la casa venne invasa dagli assalitori, il beato Luigi Giuseppe Fran\u00e7ois venne preso e gettato da una finestra. A terra fu poi picchiato e il suo cadavere, come quello degli altri, fu crudelmente profanato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luigi Giuseppe Fran\u00e7ois, l'intellettuale, fu beatificato da Papa Pio XI, il 17 ottobre 1926, con i martiri della Rivoluzione, di cui faceva parte Giovanni Enrico Gruyer, il pastore delle campagne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>GIOVANNI ENRICO GRUYER<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nato a D\u00f4le (Vosges) il 13 giugno 1734, fu ordinato sacerdote per la diocesi di Saint-Claude ed ammesso nella Congregazione della Missione il 23 gennaio del 1771. Le molteplici parrocchie di cui si \u00e8 occupata la Congregazione in Francia, soprattutto nel XVIII secolo, esigevano pastori esperti. Giovanni Enrico fu quindi destinato al ministero parrocchiale. La Rivoluzione lo sorprese a Versailles, dove era vicario nella parrocchia San Luigi. Espulso dalla parrocchia per aver rifiutato di prestare il giuramento civile, torn\u00f2 a Parigi dove il seminario di San Firmino gli apr\u00ec le porte e dove mor\u00ec il 3 settembre 1792, condividendo la sofferenza e il martirio con il beato Luigi Giuseppe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PIER RENATO ROGUE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nato a Vannes l\u201911 giugno 1758, fu ordinato prete il 21 settembre 1782. Cappellano dell\u2019opera delle \u201cDame del Ritiro\u201d, si sent\u00ec attratto dalla vocazione e dalla missione dei Preti della Missione, suoi formatori che dirigevano il grande seminario di Vannes. Ammesso nella Congregazione della Missione il 25 ottobre 1786 a Parigi, egli ritorn\u00f2 a Vannes come professore di Dogmatica. Espulso dalla legislazione rivoluzionaria, Pier Renato entr\u00f2 nella clandestinit\u00e0 per continuare il suo ministero pastorale e aiutare i cattolici perseguitati. Fu arrestato il 24 dicembre 1795 mentre portava la comunione ad un ammalato. Fu portato in prigione lo stesso giorno e vi rimase fino al 3 marzo dell'anno successivo. Fu condannato alla ghigliottina. Alla fine di questo processo iniquo in cui sua madre dovette testimoniare, fu riportato in prigione da dove scrisse la sua ultima lettera alla madre anziana e ai confratelli della sua comunit\u00e0, dicendo loro che sarebbe morto per la fede e che, in quei momenti si sentiva felice di dare la vita per Cristo. Fu giustiziato il 3 marzo 1796 sotto gli occhi della sua vecchia e santa madre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pier Renato Rogue fu beatificato da Pio XI il 10 maggio 1934.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>GIOVANNI CARLO CARON<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nacque ad Auchel, nel Pas-de-Calais, il 31 dicembre 1730. Il 30 dicembre 1750 entr\u00f2 nella Congregazione della Missione dove fece i voti nel 1752.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per ventinove anni si dedic\u00f2 al ministero delle missioni e poi divenne parroco di Coll\u00e8gien, nella diocesi di Meaux. Come molti altri, rifiut\u00f2 di firmare la Costituzione civile del clero durante la Rivoluzione francese, fu quindi espulso dalla sua parrocchia e dovette rifugiarsi a Parigi. La sua morte fu unita a quella dei martiri del crudele massacro del 2 e 3 settembre 1792.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Giovanni Carlo Caron fu beatificato da Pio XI il 17 ottobre 1926.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NICOLA COLIN<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nacque a Grenant, Haute-Marne, il 12 dicembre 1730. Pronunci\u00f2 i voti nella Congregazione della Missione nel 1749. In seguito fu nominato vicario della parrocchia di San Luigi a Versailles, dove lavor\u00f2 dal 1754 al 1770.<br>Fu anche parroco di Genevri\u00e8res, nella diocesi di Langres. Per ventidue anni esercit\u00f2 il suo ministero missionario con la reputazione di buon predicatore. La Rivoluzione lo cacci\u00f2 dal suo presbiterio. Fu sostituito da un sacerdote fedele alla Costituzione civile. Si rifugi\u00f2 a Parigi dove mor\u00ec durante il terribile massacro del 3 settembre 1792.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nicola Colin \u00e8 conosciuto per aver detto queste parole: \u00ab\u2026 come ricompensa per la mia fedelt\u00e0 alla fede, la fame, l'esilio, la prigione e forse anche la morte\u00bb.<br>Fu beatificato da Pio XI il 17 ottobre 1926.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>(Memoria liturgica 2 settembre<\/em>)<\/p>\n","protected":false},"featured_media":32246,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"origen":[37],"class_list":["post-32251","familia","type-familia","status-publish","has-post-thumbnail","hentry","origen-familia-vicenciana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beati Luigi Giuseppe Fran\u00e7ois, C.M., e i compagni martiri - Filles de la Charit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beati Luigi Giuseppe Fran\u00e7ois, C.M., e i compagni martiri - Filles de la Charit\u00e9\" \/>\n<meta property=\"og:description\" content=\"La Chiesa e la Congregazione onorano insieme i martiri della Rivoluzione Francese. A Parigi, il 3 settembre 1792, ci fu un massacro nel seminario di San Firmino, prima denominato Collegio \u201cdes Bons Enfants\u201d, che era stato acquistato da San Vincenzo de Paoli nel 1624. Questo seminario, trasformato in prigione nel 1789, divenne il quarto luogo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/\" \/>\n<meta property=\"og:site_name\" content=\"Filles de la Charit\u00e9\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-12T17:18:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/03\/Martyrs-french-revolution-CM-thumbnail-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/famiglia\\\/beato-louis-joseph-francois-c-m-y-companeros-martires\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/famiglia\\\/beato-louis-joseph-francois-c-m-y-companeros-martires\\\/\",\"name\":\"Beati Luigi Giuseppe Fran\u00e7ois, C.M., e i compagni martiri - Filles de la Charit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/famiglia\\\/beato-louis-joseph-francois-c-m-y-companeros-martires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/famiglia\\\/beato-louis-joseph-francois-c-m-y-companeros-martires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Martyrs-french-revolution-CM-thumbnail-1.jpg\",\"datePublished\":\"2024-03-02T11:55:23+00:00\",\"dateModified\":\"2024-03-12T17:18:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/famiglia\\\/beato-louis-joseph-francois-c-m-y-companeros-martires\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/famiglia\\\/beato-louis-joseph-francois-c-m-y-companeros-martires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/famiglia\\\/beato-louis-joseph-francois-c-m-y-companeros-martires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Martyrs-french-revolution-CM-thumbnail-1.jpg\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Martyrs-french-revolution-CM-thumbnail-1.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/famiglia\\\/beato-louis-joseph-francois-c-m-y-companeros-martires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"La nostra famiglia\",\"item\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/famiglia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beati Luigi Giuseppe Fran\u00e7ois, C.M., e i compagni martiri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/\",\"name\":\"Hijas de la Caridad\",\"description\":\"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies\",\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\",\"name\":\"Hijas de la Caridad\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"width\":1417,\"height\":1417,\"caption\":\"Hijas de la Caridad\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beati Luigi Giuseppe Fran\u00e7ois, C.M., e i compagni martiri - Filles de la Charit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/","og_locale":"it_IT","og_type":"article","og_title":"Beati Luigi Giuseppe Fran\u00e7ois, C.M., e i compagni martiri - Filles de la Charit\u00e9","og_description":"La Chiesa e la Congregazione onorano insieme i martiri della Rivoluzione Francese. A Parigi, il 3 settembre 1792, ci fu un massacro nel seminario di San Firmino, prima denominato Collegio \u201cdes Bons Enfants\u201d, che era stato acquistato da San Vincenzo de Paoli nel 1624. Questo seminario, trasformato in prigione nel 1789, divenne il quarto luogo [&hellip;]","og_url":"https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/","og_site_name":"Filles de la Charit\u00e9","article_modified_time":"2024-03-12T17:18:13+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/03\/Martyrs-french-revolution-CM-thumbnail-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/","url":"https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/","name":"Beati Luigi Giuseppe Fran\u00e7ois, C.M., e i compagni martiri - Filles de la Charit\u00e9","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/#primaryimage"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/03\/Martyrs-french-revolution-CM-thumbnail-1.jpg","datePublished":"2024-03-02T11:55:23+00:00","dateModified":"2024-03-12T17:18:13+00:00","breadcrumb":{"@id":"https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/#primaryimage","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/03\/Martyrs-french-revolution-CM-thumbnail-1.jpg","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/03\/Martyrs-french-revolution-CM-thumbnail-1.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/filles-de-la-charite.org\/it\/famiglia\/beato-louis-joseph-francois-c-m-y-companeros-martires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"La nostra famiglia","item":"https:\/\/filles-de-la-charite.org\/it\/famiglia\/"},{"@type":"ListItem","position":2,"name":"Beati Luigi Giuseppe Fran\u00e7ois, C.M., e i compagni martiri"}]},{"@type":"WebSite","@id":"https:\/\/filles-de-la-charite.org\/it\/#website","url":"https:\/\/filles-de-la-charite.org\/it\/","name":"Hijas de la Caridad","description":"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies","publisher":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filles-de-la-charite.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/filles-de-la-charite.org\/it\/#organization","name":"Hijas de la Caridad","url":"https:\/\/filles-de-la-charite.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","width":1417,"height":1417,"caption":"Hijas de la Caridad"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/familia\/32251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/familia"}],"about":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/types\/familia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/media\/32246"}],"wp:attachment":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/media?parent=32251"}],"wp:term":[{"taxonomy":"origen","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/origen?post=32251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}