{"id":23352,"date":"2021-04-13T09:52:18","date_gmt":"2021-04-13T07:52:18","guid":{"rendered":"https:\/\/hijascaridad.sjdigitaldemo.ovh\/missione-serawai-scolpita-nel-mio-cuore\/"},"modified":"2026-05-11T13:21:43","modified_gmt":"2026-05-11T11:21:43","slug":"missione-serawai-scolpita-nel-mio-cuore","status":"publish","type":"post","link":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/","title":{"rendered":"Missione Serawai&#8230; scolpita nel mio cuore!"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Indonesia-2-1024x768-1.jpg\" alt=\"\" class=\"wp-image-62088\" \/><\/figure><\/div>\n\n\n\n<p>Le Suore della Comunit\u00e0 Yohanes Gabriel vivono in una casa modesta, situata all\u2019interno di una piccola foresta, costruita su una collina lungo le rive del fiume Melawi a Serawai, nel Kalimantan occidentale, sull'isola del Borneo. L'elettricit\u00e0 c'\u00e8 solo di notte, dalle 18:00 alle 6:00 del mattino. Mentre le Suore aiutano nell'opera di evangelizzazione della Parrocchia andando nei villaggi su una piccola barca lungo il fiume o a piedi passando per la foresta e arrampicandosi sulle colline, la loro missione principale \u00e8 quella di servire 120 studentesse, 12-16 anni di et\u00e0, che vengono mandate dai loro genitori alla Scuola Media Superiore gestita dalla Congregazione della Missione; la maggior parte di loro sono cattoliche, alcune appartengono ad altre confessioni cristiane. Queste ragazze sognano di avere una buona istruzione superiore... ed essere in grado di aiutare le loro famiglie in futuro.\u00a0<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Indonesia-3-Kopia.jpg\" alt=\"\" class=\"wp-image-62089\" \/><\/figure><\/div>\n\n\n\n<p>Queste giovani donne possono essere considerate povere, sia spiritualmente che materialmente. Mancano di conoscenza e i valori della vita non sono, in loro, ben radicati. Camminare insieme \u00e8 difficile a causa delle differenze di cultura - tra di loro e con le suore; anche i loro genitori sono spesso motivo di conflitto.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/th-n6-1024x576-1.jpg\" alt=\"\" class=\"wp-image-62090\" \/><\/figure><\/div>\n\n\n\n<p>Per fortuna l'ambiente \u00e8 salubre: aria fresca e pulita, alberi che fanno ombra, cascate, quiete e calma - natura che non \u00e8 stata violata dalle aziende in nome del profitto e degli affari. La maggior parte della popolazione \u00e8 costituita da agricoltori e minatori che estraggono l\u2019oro dalla sabbia; alcuni sono insegnanti. Coltivano la terra manualmente, lavorando sodo \u201ccon la fatica delle braccia e il sudore della fronte\u201d per guadagnarsi il sostentamento quotidiano; il loro stile di vita \u00e8 molto semplice. Questa atmosfera aiuta le Suore a creare una vita comunitaria equilibrata.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Indonesia-5-1024x768-1.jpg\" alt=\"\" class=\"wp-image-62091\" \/><\/figure><\/div>\n\n\n\n<p>Ma c'\u00e8 del lavoro da fare! Le ragazze sono molto influenzate da ci\u00f2 che vedono e sentono dalla societ\u00e0. Cos\u00ec, insegniamo loro le competenze di base come cucinare, piantare le verdure, pulire la casa, l'igiene personale, ecc., le educhiamo anche a prendersi cura della nostra \"casa comune\" e, cosa pi\u00f9 importante, condividiamo con loro i valori vincenziani. La nostra missione \u00e8 quella di accompagnarle per essere pi\u00f9 preparate per il futuro, non solo per una vita vissuta in modo sano e sostenibile, ma anche per una vita profondamente radicata nei valori evangelici\/vincenziani.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Indonesia-6-1024x576-1.jpg\" alt=\"\" class=\"wp-image-62092\" \/><\/figure><\/div>\n\n\n\n<p>Quanto a me, vorrei scolpire nel mio cuore tutte le cose preziose della mia missione. In Cristo nulla \u00e8 impossibile! Con la Comunit\u00e0 e nella Comunit\u00e0, vivr\u00f2 fedelmente e con gioia il servizio ai poveri nella mia missione a Serawai.<\/p>\n\n\n\n<p>Suor Irene, DC<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Indonesia-7-1024x576-1.jpg\" alt=\"\" class=\"wp-image-62096\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":15741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"categories":[605],"tags":[],"class_list":["post-23352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-indonesia-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Missione Serawai... scolpita nel mio cuore! - Filles de la Charit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Missione Serawai... scolpita nel mio cuore! - Filles de la Charit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/\" \/>\n<meta property=\"og:site_name\" content=\"Filles de la Charit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-13T07:52:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T11:21:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Indonesia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/missione-serawai-scolpita-nel-mio-cuore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/missione-serawai-scolpita-nel-mio-cuore\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/person\\\/427567b2eccfc2dd7d206da186a1f438\"},\"headline\":\"Missione Serawai&#8230; scolpita nel mio cuore!\",\"datePublished\":\"2021-04-13T07:52:18+00:00\",\"dateModified\":\"2026-05-11T11:21:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/missione-serawai-scolpita-nel-mio-cuore\\\/\"},\"wordCount\":420,\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/missione-serawai-scolpita-nel-mio-cuore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Indonesia-1.jpg\",\"articleSection\":[\"Indonesia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/missione-serawai-scolpita-nel-mio-cuore\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/missione-serawai-scolpita-nel-mio-cuore\\\/\",\"name\":\"Missione Serawai... scolpita nel mio cuore! - Filles de la Charit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/missione-serawai-scolpita-nel-mio-cuore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/missione-serawai-scolpita-nel-mio-cuore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Indonesia-1.jpg\",\"datePublished\":\"2021-04-13T07:52:18+00:00\",\"dateModified\":\"2026-05-11T11:21:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/missione-serawai-scolpita-nel-mio-cuore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/missione-serawai-scolpita-nel-mio-cuore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/missione-serawai-scolpita-nel-mio-cuore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Indonesia-1.jpg\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Indonesia-1.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/missione-serawai-scolpita-nel-mio-cuore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Indonesia\",\"item\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/category\\\/indonesia-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Missione Serawai&#8230; scolpita nel mio cuore!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/\",\"name\":\"Hijas de la Caridad\",\"description\":\"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies\",\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\",\"name\":\"Hijas de la Caridad\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"width\":1417,\"height\":1417,\"caption\":\"Hijas de la Caridad\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/person\\\/427567b2eccfc2dd7d206da186a1f438\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/filles-de-la-charite.org\"],\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/author\\\/caridad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Missione Serawai... scolpita nel mio cuore! - Filles de la Charit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/","og_locale":"it_IT","og_type":"article","og_title":"Missione Serawai... scolpita nel mio cuore! - Filles de la Charit\u00e9","og_url":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/","og_site_name":"Filles de la Charit\u00e9","article_published_time":"2021-04-13T07:52:18+00:00","article_modified_time":"2026-05-11T11:21:43+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Indonesia-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/#article","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/"},"author":{"name":"admin","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/person\/427567b2eccfc2dd7d206da186a1f438"},"headline":"Missione Serawai&#8230; scolpita nel mio cuore!","datePublished":"2021-04-13T07:52:18+00:00","dateModified":"2026-05-11T11:21:43+00:00","mainEntityOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/"},"wordCount":420,"publisher":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#organization"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Indonesia-1.jpg","articleSection":["Indonesia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/","url":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/","name":"Missione Serawai... scolpita nel mio cuore! - Filles de la Charit\u00e9","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/#primaryimage"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Indonesia-1.jpg","datePublished":"2021-04-13T07:52:18+00:00","dateModified":"2026-05-11T11:21:43+00:00","breadcrumb":{"@id":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/#primaryimage","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Indonesia-1.jpg","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/Indonesia-1.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/filles-de-la-charite.org\/it\/missione-serawai-scolpita-nel-mio-cuore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Indonesia","item":"https:\/\/filles-de-la-charite.org\/it\/category\/indonesia-it\/"},{"@type":"ListItem","position":2,"name":"Missione Serawai&#8230; scolpita nel mio cuore!"}]},{"@type":"WebSite","@id":"https:\/\/filles-de-la-charite.org\/it\/#website","url":"https:\/\/filles-de-la-charite.org\/it\/","name":"Hijas de la Caridad","description":"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies","publisher":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filles-de-la-charite.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/filles-de-la-charite.org\/it\/#organization","name":"Hijas de la Caridad","url":"https:\/\/filles-de-la-charite.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","width":1417,"height":1417,"caption":"Hijas de la Caridad"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/person\/427567b2eccfc2dd7d206da186a1f438","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/filles-de-la-charite.org"],"url":"https:\/\/filles-de-la-charite.org\/it\/author\/caridad\/"}]}},"_links":{"self":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts\/23352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/comments?post=23352"}],"version-history":[{"count":2,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts\/23352\/revisions"}],"predecessor-version":[{"id":50442,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts\/23352\/revisions\/50442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/media\/15741"}],"wp:attachment":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/media?parent=23352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/categories?post=23352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/tags?post=23352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}