{"id":41291,"date":"2024-12-29T17:14:46","date_gmt":"2024-12-29T16:14:46","guid":{"rendered":"https:\/\/filles-de-la-charite.org\/?p=41291"},"modified":"2026-05-11T13:43:48","modified_gmt":"2026-05-11T11:43:48","slug":"reunion-de-navidad-5","status":"publish","type":"post","link":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/","title":{"rendered":"Incontro di Natale"},"content":{"rendered":"\n<p>L'incontro natalizio dei familiari e degli amici del Centro per persone con bisogni speciali di Ignacowo, in Polonia, \u00e8 diventato un appuntamento emozionante che occupa un posto speciale nel nostro calendario. L'entusiasmo e le telefonate di richiesta di informazioni circa la data di questa festa ci riempiono di gioia molto prima dell'invio degli inviti ufficiali.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0025-1024x683.jpg\" alt=\"\" class=\"wp-image-41275\" srcset=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0025-980x653.jpg 980w, https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0025-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p>Nel nostro centro cerchiamo di creare un'atmosfera in cui l'incontro sia tra persone, non tra funzionari o dipendenti. Sembra di essere riuscite nell\u2019intento, come dimostrano le parole dei nostri ospiti, che provengono da ambienti diversi: \u00abQui mi sento a casa\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0021-1024x683.jpg\" alt=\"\" class=\"wp-image-41281\" srcset=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0021-980x653.jpg 980w, https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0021-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p>Come riusciamo a creare questa atmosfera? Le prove dedicate alla rappresentazione della Nativit\u00e0, le decorazioni curate nei minimi dettagli e la preparazione della tavola sono il frutto dell'impegno gioioso di bambini e adulti, i padroni di casa di questa serata. Poi si tratta della gioia di incontrarsi, di scambiarsi parole ricche di calore umano, di cantare canzoni e di godere della reciproca compagnia. Non importa se la paura del palcoscenico toglie la voce a una timida attrice o se il tono alto di un bambino autistico smorza gli auguri dei padroni di casa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0024-1024x682.jpg\" alt=\"\" class=\"wp-image-41269\" srcset=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0024-980x653.jpg 980w, https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0024-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p>Il valore autentico del nostro incontro non sta nella precisione delle esibizioni, ma nell'amore e nella dedizione con cui i nostri alunni hanno preparato l'evento. \u00c8 un momento di felicit\u00e0 per i bambini e di profonda emozione per i genitori, che ci permette di mettere da parte per un attimo le difficolt\u00e0 della vita quotidiana e di godere dello stare insieme. E ci\u00f2 che ci unisce \u00e8 questo grande avvenimento: la nascita del Figlio di Dio.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0023-683x1024.jpg\" alt=\"\" class=\"wp-image-41263\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":41260,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"categories":[703],"tags":[],"class_list":["post-41291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varsavia-polonia-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Incontro di Natale - Filles de la Charit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incontro di Natale - Filles de la Charit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Filles de la Charit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-29T16:14:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T11:43:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SOR MARTA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"SOR MARTA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/reunion-de-navidad-5\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/reunion-de-navidad-5\\\/\"},\"author\":{\"name\":\"SOR MARTA\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/person\\\/0c922b6ca71280639858d297b3a7209f\"},\"headline\":\"Incontro di Natale\",\"datePublished\":\"2024-12-29T16:14:46+00:00\",\"dateModified\":\"2026-05-11T11:43:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/reunion-de-navidad-5\\\/\"},\"wordCount\":273,\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/reunion-de-navidad-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/IMG-20241220-WA0022.jpg\",\"articleSection\":[\"Varsavia - Polonia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/reunion-de-navidad-5\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/reunion-de-navidad-5\\\/\",\"name\":\"Incontro di Natale - Filles de la Charit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/reunion-de-navidad-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/reunion-de-navidad-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/IMG-20241220-WA0022.jpg\",\"datePublished\":\"2024-12-29T16:14:46+00:00\",\"dateModified\":\"2026-05-11T11:43:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/reunion-de-navidad-5\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/reunion-de-navidad-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/reunion-de-navidad-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/IMG-20241220-WA0022.jpg\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/IMG-20241220-WA0022.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/reunion-de-navidad-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Varsavia - Polonia\",\"item\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/category\\\/varsavia-polonia-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incontro di Natale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/\",\"name\":\"Hijas de la Caridad\",\"description\":\"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies\",\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\",\"name\":\"Hijas de la Caridad\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"width\":1417,\"height\":1417,\"caption\":\"Hijas de la Caridad\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/person\\\/0c922b6ca71280639858d297b3a7209f\",\"name\":\"SOR MARTA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g\",\"caption\":\"SOR MARTA\"},\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/author\\\/martaemn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incontro di Natale - Filles de la Charit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/","og_locale":"it_IT","og_type":"article","og_title":"Incontro di Natale - Filles de la Charit\u00e9","og_url":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/","og_site_name":"Filles de la Charit\u00e9","article_published_time":"2024-12-29T16:14:46+00:00","article_modified_time":"2026-05-11T11:43:48+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0022.jpg","type":"image\/jpeg"}],"author":"SOR MARTA","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"SOR MARTA","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/#article","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/"},"author":{"name":"SOR MARTA","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/person\/0c922b6ca71280639858d297b3a7209f"},"headline":"Incontro di Natale","datePublished":"2024-12-29T16:14:46+00:00","dateModified":"2026-05-11T11:43:48+00:00","mainEntityOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/"},"wordCount":273,"publisher":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#organization"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0022.jpg","articleSection":["Varsavia - Polonia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/","url":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/","name":"Incontro di Natale - Filles de la Charit\u00e9","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/#primaryimage"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0022.jpg","datePublished":"2024-12-29T16:14:46+00:00","dateModified":"2026-05-11T11:43:48+00:00","breadcrumb":{"@id":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/#primaryimage","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0022.jpg","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2024\/12\/IMG-20241220-WA0022.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/filles-de-la-charite.org\/it\/reunion-de-navidad-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Varsavia - Polonia","item":"https:\/\/filles-de-la-charite.org\/it\/category\/varsavia-polonia-it\/"},{"@type":"ListItem","position":2,"name":"Incontro di Natale"}]},{"@type":"WebSite","@id":"https:\/\/filles-de-la-charite.org\/it\/#website","url":"https:\/\/filles-de-la-charite.org\/it\/","name":"Hijas de la Caridad","description":"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies","publisher":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filles-de-la-charite.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/filles-de-la-charite.org\/it\/#organization","name":"Hijas de la Caridad","url":"https:\/\/filles-de-la-charite.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","width":1417,"height":1417,"caption":"Hijas de la Caridad"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/person\/0c922b6ca71280639858d297b3a7209f","name":"SOR MARTA","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g","caption":"SOR MARTA"},"url":"https:\/\/filles-de-la-charite.org\/it\/author\/martaemn\/"}]}},"_links":{"self":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts\/41291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/comments?post=41291"}],"version-history":[{"count":4,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts\/41291\/revisions"}],"predecessor-version":[{"id":51114,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts\/41291\/revisions\/51114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/media\/41260"}],"wp:attachment":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/media?parent=41291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/categories?post=41291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/tags?post=41291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}