{"id":43886,"date":"2025-06-21T01:35:00","date_gmt":"2025-06-20T23:35:00","guid":{"rendered":"https:\/\/filles-de-la-charite.org\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil\/"},"modified":"2026-05-11T13:47:28","modified_gmt":"2026-05-11T11:47:28","slug":"x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5","status":"publish","type":"post","link":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/","title":{"rendered":"10\u00ba Incontro Interprovinciale del Servizio di Animazione Vocazionale Vincenziana in Brasile"},"content":{"rendered":"\n<p>Incoraggiati dalla speranza che non delude, i rappresentanti delle sei Province delle Figlie della Carit\u00e0 di san Vincenzo de' Paoli, i Preti della Congregazione della Missione, le Suore di san Vincenzo de' Paoli di Gysegem, i religiosi di san Vincenzo de' Paoli e i membri della Casa della Fraternit\u00e0 di Ranquines si sono riuniti presso la Casa Provinciale di Nostra Signora delle Grazie a Recife, Pernambuco, dal 30 aprile al 4 maggio 2025 per valutare i progressi di questo servizio negli ultimi tre anni, per riflettere sulle sfide contemporanee nell'animazione vocazionale e delineare strategie per i prossimi tre anni.<\/p>\n\n\n\n<p><strong>TEMA ISPIRATORE<\/strong><\/p>\n\n\n\n<p>Il tema guida dell'incontro era \"<strong>Gioiosi nella speranza, gettiamo le reti<\/strong>\", e come Parola ispiratrice: <strong>\u00ab<\/strong><strong>Seguitemi, vi far\u00f2 pescatori di uomini<\/strong><strong>\u00bb<\/strong> (Mt 4,19).<\/p>\n\n\n\n<p>Questo tema ha guidato le riflessioni dell'incontro. Proprio come Ges\u00f9 ha chiamato i suoi discepoli a seguirlo e a diventare pescatori di uomini, gli animatori vocazionali sono chiamati a proclamare il Vangelo e a ispirare i giovani a seguire Cristo, gettando le loro reti con gioia e speranza.<\/p>\n\n\n\n<p>L'avvenimento ha visto la partecipazione di relatori di spicco che hanno offerto preziose riflessioni sulla vocazione e sull'evangelizzazione:<\/p>\n\n\n\n<p>Con il tema <strong>\"Gioiosi nella speranza, gettiamo le reti\"<\/strong>, Padre Edicarlos Alves, OMI, ha sottolineato che un animatore vocazionale deve essere, soprattutto, una persona gioiosa. Ha evidenziato che la sua prima missione \u00e8 pregare per le vocazioni, creare spazi di spiritualit\u00e0 e promuovere momenti di riflessione personale, comunitaria ed ecclesiale. Inoltre, ha sottolineato:<\/p>\n\n\n\n<p>\u2022 <strong>Chiarezza nell'identit\u00e0 carismatica della Vocazione vincenziana<\/strong>.<\/p>\n\n\n\n<p>\u2022<strong>Vicinanza e coinvolgimento con i giovani, promuovendo un'accoglienza e un'interazione &nbsp;autentiche.<\/strong><\/p>\n\n\n\n<p>\u2022 <strong>Uso strategico dei media digitali per la comunicazione e l'evangelizzazione.<\/strong><\/p>\n\n\n\n<p>Fratel M\u00e1rcio Ferreira, dei Maristi, ha discusso le sfide e le prospettive dell'accompagnamento vocazionale in Brasile, sostenendo la transizione da una mentalit\u00e0 vocazionale a una spiritualit\u00e0 vocazionale, promuovendo cos\u00ec una solida cultura vocazionale.<\/p>\n\n\n\n<p>Basandosi su Luca 24 (i discepoli di Emmaus), ha evidenziato i passaggi chiave della pedagogia vocazionale di Ges\u00f9:<\/p>\n\n\n\n<p>\u2022 <strong>Avvicinarsi con tenerezza e attenzione.<\/strong><\/p>\n\n\n\n<p><strong>\u2022 Ascolto profondo ed empatico.<\/strong><\/p>\n\n\n\n<p><strong>\u2022 Costruire un rapporto di fiducia tra animatori e giovani.<\/strong><\/p>\n\n\n\n<p><strong>\u2022 Definire chiaramente i criteri di valutazione della chiamata vocazionale.<\/strong><\/p>\n\n\n\n<p>Padre Wellington Jean Souza ha condiviso riflessioni sull'affettivit\u00e0 e sulla sessualit\u00e0 nell'accompagnamento vocazionale. Ha sottolineato l'importanza di vivere la consacrazione nel rispetto dell'identit\u00e0 sessuale individuale e ha affrontato la necessit\u00e0 di:<\/p>\n\n\n\n<p>\u2022 <strong>Comprendere i giovani in modo olistico, senza pregiudizi.<\/strong><\/p>\n\n\n\n<p><strong>\u2022 Sviluppare un ascolto attivo e accogliente, promuovendo la fiducia.<\/strong><\/p>\n\n\n\n<p><strong>\u2022 \u200b\u200bCreare spazi aperti, incoraggiando un accompagnamento solido e strutturato.<\/strong><\/p>\n\n\n\n<p><strong>PELLEGRINAGGIO E SPIRITUALIT\u00c0<\/strong><\/p>\n\n\n\n<p>Come pellegrini della speranza, i partecipanti hanno visitato importanti luoghi storici di fede, tra cui:<\/p>\n\n\n\n<p>\u2022 <strong>Casa Memoriale Dom Helder C\u00e2mara<\/strong><\/p>\n\n\n\n<p><strong>\u2022 S\u00e9, Chiesa dell'Arcidiocesi di Olinda e Recife, dove \u00e8 sepolto Dom Helder<\/strong><\/p>\n\n\n\n<p><strong>\u2022 Convento S\u00e3o F\u00e9lix de Cantalice, dove riposa Fra Dami\u00e3o de Bozzano<\/strong><\/p>\n\n\n\n<p>In questi luoghi sacri, hanno celebrato l'Eucaristia, rafforzando la comunione e la loro missione di evangelizzazione.<\/p>\n\n\n\n<p><strong>IMPEGNI PER I PROSSIMI ANNI<\/strong><\/p>\n\n\n\n<p>Ispirati dallo Spirito Santo e dalle intuizioni acquisite durante l'incontro, i partecipanti hanno assunto tre impegni fondamentali per rafforzare la cultura vocazionale:<\/p>\n\n\n\n<p>\u2022 <strong>DARE PRIORIT\u00c0<\/strong> alla cultura vocazionale all'interno delle comunit\u00e0, approfondendo la spiritualit\u00e0 e intensificando la preghiera personale e comunitaria.<\/p>\n\n\n\n<p>\u2022 <strong>\u200b\u200bPROMUOVERE<\/strong> una formazione specifica per gli animatori vocazionali, affrontando temi di attualit\u00e0 come l'affettivit\u00e0 e la sessualit\u00e0.<\/p>\n\n\n\n<p>\u2022 <strong>SVILUPPARE<\/strong> un piano strategico unitario per il Servizio di Animazione Vocazionale vincenziana (SAVV), che comprenda fasi chiave come il risveglio, il discernimento, la crescita e l'accompagnamento.<\/p>\n\n\n\n<p><strong>GRATITUDINE E SPERANZA PER IL FUTURO<\/strong><\/p>\n\n\n\n<p>A Dio offriamo la nostra lode e la nostra gratitudine per le benedizioni che abbiamo ricevuto. Il decimo Incontro Interprovinciale \u00e8 stato un momento di apprendimento, di condivisione di esperienze e di rinnovato incoraggiamento per la missione.<\/p>\n\n\n\n<p>Maria, Madre di tutte le Vocazioni, interceda per questo prezioso servizio affinch\u00e9 gli animatori vocazionali, pieni di gioia ed entusiasmo, raggiungano i giovani con zelo missionario, gettando le reti con fede e speranza!<\/p>\n\n\n\n<div class=\"wp-block-responsive-lightbox-gallery\"><div class=\"et_pb_slider et_pb_slider_fullwidth_off et_pb_gallery_post_type\">\n\t\t\t\t<div class=\"et_pb_slides\">\n\t\t\t\t\t<div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.49.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.52-2.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.52-3.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.53.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.53-2.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.54.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.54-1.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.43.56.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.47.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.48.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.52.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.51-2.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.51-1.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.49-1.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.49-2.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.49-3.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.49-4.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.50.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.50-1.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.50-3.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.50-4.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.51.jpeg);\"><\/div><div class=\"et_pb_slide\" style=\"background: url(https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.48-1.jpeg);\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":43877,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"categories":[854],"tags":[],"class_list":["post-43886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasile"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10\u00ba Incontro Interprovinciale del Servizio di Animazione Vocazionale Vincenziana in Brasile - Filles de la Charit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10\u00ba Incontro Interprovinciale del Servizio di Animazione Vocazionale Vincenziana in Brasile - Filles de la Charit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Filles de la Charit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-20T23:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T11:47:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.48-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SOR MARTA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"SOR MARTA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\\\/\"},\"author\":{\"name\":\"SOR MARTA\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/person\\\/0c922b6ca71280639858d297b3a7209f\"},\"headline\":\"10\u00ba Incontro Interprovinciale del Servizio di Animazione Vocazionale Vincenziana in Brasile\",\"datePublished\":\"2025-06-20T23:35:00+00:00\",\"dateModified\":\"2026-05-11T11:47:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\\\/\"},\"wordCount\":662,\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/WhatsApp-Image-2025-06-21-at-01.44.48-1.jpeg\",\"articleSection\":[\"Brasile\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\\\/\",\"name\":\"10\u00ba Incontro Interprovinciale del Servizio di Animazione Vocazionale Vincenziana in Brasile - Filles de la Charit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/WhatsApp-Image-2025-06-21-at-01.44.48-1.jpeg\",\"datePublished\":\"2025-06-20T23:35:00+00:00\",\"dateModified\":\"2026-05-11T11:47:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/WhatsApp-Image-2025-06-21-at-01.44.48-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/WhatsApp-Image-2025-06-21-at-01.44.48-1.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Brasile\",\"item\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/category\\\/brasile\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10\u00ba Incontro Interprovinciale del Servizio di Animazione Vocazionale Vincenziana in Brasile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/\",\"name\":\"Hijas de la Caridad\",\"description\":\"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies\",\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\",\"name\":\"Hijas de la Caridad\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"width\":1417,\"height\":1417,\"caption\":\"Hijas de la Caridad\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/person\\\/0c922b6ca71280639858d297b3a7209f\",\"name\":\"SOR MARTA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g\",\"caption\":\"SOR MARTA\"},\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/author\\\/martaemn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10\u00ba Incontro Interprovinciale del Servizio di Animazione Vocazionale Vincenziana in Brasile - Filles de la Charit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/","og_locale":"it_IT","og_type":"article","og_title":"10\u00ba Incontro Interprovinciale del Servizio di Animazione Vocazionale Vincenziana in Brasile - Filles de la Charit\u00e9","og_url":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/","og_site_name":"Filles de la Charit\u00e9","article_published_time":"2025-06-20T23:35:00+00:00","article_modified_time":"2026-05-11T11:47:28+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.48-1.jpeg","type":"image\/jpeg"}],"author":"SOR MARTA","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"SOR MARTA","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/#article","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/"},"author":{"name":"SOR MARTA","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/person\/0c922b6ca71280639858d297b3a7209f"},"headline":"10\u00ba Incontro Interprovinciale del Servizio di Animazione Vocazionale Vincenziana in Brasile","datePublished":"2025-06-20T23:35:00+00:00","dateModified":"2026-05-11T11:47:28+00:00","mainEntityOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/"},"wordCount":662,"publisher":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#organization"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.48-1.jpeg","articleSection":["Brasile"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/","url":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/","name":"10\u00ba Incontro Interprovinciale del Servizio di Animazione Vocazionale Vincenziana in Brasile - Filles de la Charit\u00e9","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/#primaryimage"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.48-1.jpeg","datePublished":"2025-06-20T23:35:00+00:00","dateModified":"2026-05-11T11:47:28+00:00","breadcrumb":{"@id":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/#primaryimage","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.48-1.jpeg","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-21-at-01.44.48-1.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/filles-de-la-charite.org\/it\/x-encuentro-interprovincial-del-servicio-de-animacion-vocacional-vicenciana-en-brasil-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Brasile","item":"https:\/\/filles-de-la-charite.org\/it\/category\/brasile\/"},{"@type":"ListItem","position":2,"name":"10\u00ba Incontro Interprovinciale del Servizio di Animazione Vocazionale Vincenziana in Brasile"}]},{"@type":"WebSite","@id":"https:\/\/filles-de-la-charite.org\/it\/#website","url":"https:\/\/filles-de-la-charite.org\/it\/","name":"Hijas de la Caridad","description":"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies","publisher":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filles-de-la-charite.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/filles-de-la-charite.org\/it\/#organization","name":"Hijas de la Caridad","url":"https:\/\/filles-de-la-charite.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","width":1417,"height":1417,"caption":"Hijas de la Caridad"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/person\/0c922b6ca71280639858d297b3a7209f","name":"SOR MARTA","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g","caption":"SOR MARTA"},"url":"https:\/\/filles-de-la-charite.org\/it\/author\/martaemn\/"}]}},"_links":{"self":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts\/43886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/comments?post=43886"}],"version-history":[{"count":2,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts\/43886\/revisions"}],"predecessor-version":[{"id":51222,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts\/43886\/revisions\/51222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/media\/43877"}],"wp:attachment":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/media?parent=43886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/categories?post=43886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/tags?post=43886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}