{"id":47360,"date":"2025-10-10T18:17:43","date_gmt":"2025-10-10T16:17:43","guid":{"rendered":"https:\/\/filles-de-la-charite.org\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza\/"},"modified":"2026-05-11T13:52:12","modified_gmt":"2026-05-11T11:52:12","slug":"encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2","status":"publish","type":"post","link":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/","title":{"rendered":"Incontro Giubilare delle Figlie della Carit\u00e0 &#8220;Insieme con speranza&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Pi\u00f9 di 1.300 chilometri di distanza, una lingua diversa, ma lo stesso spirito, la stessa ispirazione, lo stesso desiderio di vivere insieme l'Anno Giubilare per andare avanti con speranza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Di recente, l\u2019\u00e9quipe del sito web della Compagnia ha iniziato a preparare un articolo sul pellegrinaggio delle Suore della Comunit\u00e0 San Giuseppe dalla Casa Madre di Parigi alla Cattedrale di Notre Dame, quando il 3 ottobre, le Figlie della Carit\u00e0 di quattro comunit\u00e0 della Provincia di Che\u0142mno - Pozna\u0144 si sono recate in pellegrinaggio \"Insieme con speranza\" per trascorrere una giornata presso la Casa d Riposo dei Missionari Verbiti a Chludowo (Polonia centrale).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/Zdjecie-WhatsApp-2025-10-03-o-20.16.38_6cec645c-768x1024.jpg\" alt=\"\" class=\"wp-image-47311\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La maggior parte del nostro gruppo era composta da Suore anziane della Comunit\u00e0 della Serva di Dio Stanis\u0142awa Barbara Samulowska di Pozna\u0144. Nonostante l'et\u00e0 e i problemi di salute, sono partite con gioia ed entusiasmo. Durante il viaggio, eravamo accompagnate da canti devozionali e, come si addice al mese di ottobre, dalla preghiera del Rosario.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/Zdjecie-WhatsApp-2025-10-03-o-19.48.29_b331993f-1024x577.jpg\" alt=\"\" class=\"wp-image-47305\" srcset=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/Zdjecie-WhatsApp-2025-10-03-o-19.48.29_b331993f-980x552.jpg 980w, https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/Zdjecie-WhatsApp-2025-10-03-o-19.48.29_b331993f-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Con preghiere e canti, siamo giunte a destinazione, dove i Missionari Verbiti ci hanno invitate per un caff\u00e8. Durante l'incontro, abbiamo parlato della storia e dei carismi delle nostre rispettive Congregazioni. Abbiamo poi avuto l'opportunit\u00e0 di visitare il Museo Missionario e ammirare le mostre presenti, che ci hanno ricordato i grandi missionari, martiri e santi della Famiglia vincenziana. Siamo rimaste particolarmente colpite dalle parole del Servo di Dio, Padre Marian \u017belazek, missionario tra i lebbrosi, a cui \u00e8 dedicata gran parte del museo: \u00ab<em>Non \u00e8 difficile essere buoni, basta volerlo\u00bb.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/Zdjecie-WhatsApp-2025-10-03-o-19.48.29_442faa5d-1024x577.jpg\" alt=\"\" class=\"wp-image-47279\" srcset=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/Zdjecie-WhatsApp-2025-10-03-o-19.48.29_442faa5d-980x552.jpg 980w, https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/Zdjecie-WhatsApp-2025-10-03-o-19.48.29_442faa5d-480x270.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pi\u00f9 tardi, abbiamo fatto una passeggiata nel grande parco. Alberi, vecchi di trecento anni o pi\u00f9, ci hanno incoraggiato ad ammirare la bellezza del creato. Le Suore pi\u00f9 anziane hanno fatto una passeggiata con gioia, senza lasciarsi scoraggiare dal terreno accidentato, sostenendosi a vicenda con semplicit\u00e0 e accettando l'aiuto offerto. Erano dei veri e propri esercizi pratici per andare avanti con speranza!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A mezzogiorno ci siamo riuniti nella cappella della Casa di Riposo per la Santa Messa. Durante l'omelia, Padre Kazimierz ci ha incoraggiato a esaminare attentamente le nostre azioni e a valutare, soprattutto, se sono gradite a Dio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/20251003_122508-1024x768.jpg\" alt=\"\" class=\"wp-image-47291\" srcset=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/20251003_122508-980x735.jpg 980w, https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/20251003_122508-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dopo la messa, abbiamo condiviso un pasto insieme, che ci ha dato l'opportunit\u00e0 di scambiare impressioni, porre domande e gioire della ricchezza dei carismi di entrambe le Congregazioni.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/20251003_132833-1024x768.jpg\" alt=\"\" class=\"wp-image-47267\" srcset=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/20251003_132833-980x735.jpg 980w, https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/20251003_132833-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Siamo rientrate piene di nuova energia, ricolme di gratitudine verso Dio per averci dato l\u2019opportunit\u00e0 di partecipare a questo incontro, grate a Suor Magdalena, Assistente provinciale, e alla Suor Servente Suor Anna, per l'idea di questo pellegrinaggio e la sua efficiente organizzazione. \u00c8 stato un pellegrinaggio gioioso, \"Insieme con speranza\", che, per opera dello Spirito Santo, ha coinciso con un'iniziativa simile delle nostre Sorelle in Francia.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":47288,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"categories":[780],"tags":[],"class_list":["post-47360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chelmno-poznan-polonia-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Incontro Giubilare delle Figlie della Carit\u00e0 &quot;Insieme con speranza&quot; - Filles de la Charit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incontro Giubilare delle Figlie della Carit\u00e0 &quot;Insieme con speranza&quot; - Filles de la Charit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Filles de la Charit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-10T16:17:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T11:52:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/20251003_110354-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SOR MARTA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"SOR MARTA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\\\/\"},\"author\":{\"name\":\"SOR MARTA\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/person\\\/0c922b6ca71280639858d297b3a7209f\"},\"headline\":\"Incontro Giubilare delle Figlie della Carit\u00e0 &#8220;Insieme con speranza&#8221;\",\"datePublished\":\"2025-10-10T16:17:43+00:00\",\"dateModified\":\"2026-05-11T11:52:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\\\/\"},\"wordCount\":457,\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/20251003_110354-scaled.jpg\",\"articleSection\":[\"Chelmno-Poznan - Pol\u00f4nia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\\\/\",\"name\":\"Incontro Giubilare delle Figlie della Carit\u00e0 \\\"Insieme con speranza\\\" - Filles de la Charit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/20251003_110354-scaled.jpg\",\"datePublished\":\"2025-10-10T16:17:43+00:00\",\"dateModified\":\"2026-05-11T11:52:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/20251003_110354-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/20251003_110354-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Chelmno-Poznan - Pol\u00f4nia\",\"item\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/category\\\/chelmno-poznan-polonia-it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incontro Giubilare delle Figlie della Carit\u00e0 &#8220;Insieme con speranza&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/\",\"name\":\"Hijas de la Caridad\",\"description\":\"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies\",\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\",\"name\":\"Hijas de la Caridad\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"width\":1417,\"height\":1417,\"caption\":\"Hijas de la Caridad\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/person\\\/0c922b6ca71280639858d297b3a7209f\",\"name\":\"SOR MARTA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g\",\"caption\":\"SOR MARTA\"},\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/author\\\/martaemn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incontro Giubilare delle Figlie della Carit\u00e0 \"Insieme con speranza\" - Filles de la Charit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/","og_locale":"it_IT","og_type":"article","og_title":"Incontro Giubilare delle Figlie della Carit\u00e0 \"Insieme con speranza\" - Filles de la Charit\u00e9","og_url":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/","og_site_name":"Filles de la Charit\u00e9","article_published_time":"2025-10-10T16:17:43+00:00","article_modified_time":"2026-05-11T11:52:12+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/20251003_110354-scaled.jpg","type":"image\/jpeg"}],"author":"SOR MARTA","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"SOR MARTA","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/#article","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/"},"author":{"name":"SOR MARTA","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/person\/0c922b6ca71280639858d297b3a7209f"},"headline":"Incontro Giubilare delle Figlie della Carit\u00e0 &#8220;Insieme con speranza&#8221;","datePublished":"2025-10-10T16:17:43+00:00","dateModified":"2026-05-11T11:52:12+00:00","mainEntityOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/"},"wordCount":457,"publisher":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#organization"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/20251003_110354-scaled.jpg","articleSection":["Chelmno-Poznan - Pol\u00f4nia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/","url":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/","name":"Incontro Giubilare delle Figlie della Carit\u00e0 \"Insieme con speranza\" - Filles de la Charit\u00e9","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/#primaryimage"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/20251003_110354-scaled.jpg","datePublished":"2025-10-10T16:17:43+00:00","dateModified":"2026-05-11T11:52:12+00:00","breadcrumb":{"@id":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/#primaryimage","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/20251003_110354-scaled.jpg","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/10\/20251003_110354-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/filles-de-la-charite.org\/it\/encuentro-jubilar-de-las-hijas-de-la-caridad-juntas-con-esperanza-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Chelmno-Poznan - Pol\u00f4nia","item":"https:\/\/filles-de-la-charite.org\/it\/category\/chelmno-poznan-polonia-it\/"},{"@type":"ListItem","position":2,"name":"Incontro Giubilare delle Figlie della Carit\u00e0 &#8220;Insieme con speranza&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/filles-de-la-charite.org\/it\/#website","url":"https:\/\/filles-de-la-charite.org\/it\/","name":"Hijas de la Caridad","description":"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies","publisher":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filles-de-la-charite.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/filles-de-la-charite.org\/it\/#organization","name":"Hijas de la Caridad","url":"https:\/\/filles-de-la-charite.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","width":1417,"height":1417,"caption":"Hijas de la Caridad"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/person\/0c922b6ca71280639858d297b3a7209f","name":"SOR MARTA","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g","caption":"SOR MARTA"},"url":"https:\/\/filles-de-la-charite.org\/it\/author\/martaemn\/"}]}},"_links":{"self":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts\/47360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/comments?post=47360"}],"version-history":[{"count":2,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts\/47360\/revisions"}],"predecessor-version":[{"id":51363,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/posts\/47360\/revisions\/51363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/media\/47288"}],"wp:attachment":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/media?parent=47360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/categories?post=47360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/tags?post=47360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}