{"id":30584,"date":"2023-10-31T10:44:12","date_gmt":"2023-10-31T09:44:12","guid":{"rendered":"https:\/\/hijascaridad.sjdigitaldemo.ovh\/service\/migranti-e-rifugiati\/"},"modified":"2024-02-25T18:26:59","modified_gmt":"2024-02-25T17:26:59","slug":"migranti-e-rifugiati","status":"publish","type":"service","link":"https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/","title":{"rendered":"Rifugiati e migranti"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">All\u2019epoca dei nostri Fondatori, le guerre erano la causa dell\u2019esodo di migliaia di persone di ogni et\u00e0 e classe sociale che arrivavano a Parigi. San Vincenzo ha fatto di tutto per alleviare queste persone in difficolt\u00e0 ed esprimere loro tutta la sua tenerezza.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Oggi, la fame, le catastrofi naturali, i regimi totalitari e corrotti e i conflitti mondiali hanno contribuito ad aumentare il numero degli sfollati, comprese le famiglie, alla ricerca di una vita diversa, di un lavoro e di un alloggio. Il loro sogno di un'esistenza migliore e rispettosa della loro dignit\u00e0 si trasforma spesso in un incubo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infatti, arrivano senza soldi, senza contatti, n\u00e9 alloggio, n\u00e9 conoscenza della lingua. A volte si sono indebitate per pagare trafficanti senza scrupoli. A causa del loro isolamento, diventano facili bersagli per tutti i profittatori che violano i loro diritti. Possono arrivare a commettere reati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ispirate dalla Parola di Dio, riconosciamo in esse la presenza della Sacra Famiglia nel suo esilio in Egitto e partecipiamo alla difesa e al rispetto dei diritti dei migranti e dei rifugiati, alla loro protezione e promozione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noi offriamo loro:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>un sostegno amichevole per facilitare il loro adattamento<\/li>\n\n\n\n<li>risorse di base<\/li>\n\n\n\n<li>assistenza nelle procedure legali<\/li>\n\n\n\n<li>un alloggio<\/li>\n\n\n\n<li>corsi di lingua<\/li>\n\n\n\n<li>aiuto nella ricerca di un\u2019abitazione<\/li>\n<\/ul>\n","protected":false},"featured_media":2042,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"class_list":["post-30584","service","type-service","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rifugiati e migranti - Filles de la Charit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rifugiati e migranti - Filles de la Charit\u00e9\" \/>\n<meta property=\"og:description\" content=\"All\u2019epoca dei nostri Fondatori, le guerre erano la causa dell\u2019esodo di migliaia di persone di ogni et\u00e0 e classe sociale che arrivavano a Parigi. San Vincenzo ha fatto di tutto per alleviare queste persone in difficolt\u00e0 ed esprimere loro tutta la sua tenerezza. Oggi, la fame, le catastrofi naturali, i regimi totalitari e corrotti e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/\" \/>\n<meta property=\"og:site_name\" content=\"Filles de la Charit\u00e9\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-25T17:26:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/04\/migrantes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/service\\\/migranti-e-rifugiati\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/service\\\/migranti-e-rifugiati\\\/\",\"name\":\"Rifugiati e migranti - Filles de la Charit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/service\\\/migranti-e-rifugiati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/service\\\/migranti-e-rifugiati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/migrantes.jpg\",\"datePublished\":\"2023-10-31T09:44:12+00:00\",\"dateModified\":\"2024-02-25T17:26:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/service\\\/migranti-e-rifugiati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/service\\\/migranti-e-rifugiati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/service\\\/migranti-e-rifugiati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/migrantes.jpg\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/migrantes.jpg\",\"width\":1920,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/service\\\/migranti-e-rifugiati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Services\",\"item\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/service\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rifugiati e migranti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/\",\"name\":\"Hijas de la Caridad\",\"description\":\"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies\",\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#organization\",\"name\":\"Hijas de la Caridad\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"width\":1417,\"height\":1417,\"caption\":\"Hijas de la Caridad\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rifugiati e migranti - Filles de la Charit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/","og_locale":"it_IT","og_type":"article","og_title":"Rifugiati e migranti - Filles de la Charit\u00e9","og_description":"All\u2019epoca dei nostri Fondatori, le guerre erano la causa dell\u2019esodo di migliaia di persone di ogni et\u00e0 e classe sociale che arrivavano a Parigi. San Vincenzo ha fatto di tutto per alleviare queste persone in difficolt\u00e0 ed esprimere loro tutta la sua tenerezza. Oggi, la fame, le catastrofi naturali, i regimi totalitari e corrotti e [&hellip;]","og_url":"https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/","og_site_name":"Filles de la Charit\u00e9","article_modified_time":"2024-02-25T17:26:59+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/04\/migrantes.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/","url":"https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/","name":"Rifugiati e migranti - Filles de la Charit\u00e9","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/#primaryimage"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/04\/migrantes.jpg","datePublished":"2023-10-31T09:44:12+00:00","dateModified":"2024-02-25T17:26:59+00:00","breadcrumb":{"@id":"https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/#primaryimage","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/04\/migrantes.jpg","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/04\/migrantes.jpg","width":1920,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/filles-de-la-charite.org\/it\/service\/migranti-e-rifugiati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Services","item":"https:\/\/filles-de-la-charite.org\/it\/service\/"},{"@type":"ListItem","position":2,"name":"Rifugiati e migranti"}]},{"@type":"WebSite","@id":"https:\/\/filles-de-la-charite.org\/it\/#website","url":"https:\/\/filles-de-la-charite.org\/it\/","name":"Hijas de la Caridad","description":"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies","publisher":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filles-de-la-charite.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/filles-de-la-charite.org\/it\/#organization","name":"Hijas de la Caridad","url":"https:\/\/filles-de-la-charite.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","width":1417,"height":1417,"caption":"Hijas de la Caridad"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/service\/30584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/types\/service"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/media\/2042"}],"wp:attachment":[{"href":"https:\/\/filles-de-la-charite.org\/it\/wp-json\/wp\/v2\/media?parent=30584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}