{"id":25289,"date":"2022-04-30T22:00:00","date_gmt":"2022-04-30T20:00:00","guid":{"rendered":"https:\/\/hijascaridad.sjdigitaldemo.ovh\/projecto-aprender-trabalhar\/"},"modified":"2026-05-11T13:28:01","modified_gmt":"2026-05-11T11:28:01","slug":"projecto-aprender-trabalhar","status":"publish","type":"post","link":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/","title":{"rendered":"Projecto &#8220;Aprender-Trabalhar&#8221;"},"content":{"rendered":"\n<p>A Beata Comunidade Rosalie Rendu das Filhas da Caridade de S. Vicente de Paulo, composta por tr\u00eas Irm\u00e3s chegou \u00e0 Papua Nova Guin\u00e9 (PNG) em Janeiro de 2019, a pedido do Bispo Rolando C. Santos, CM, DD para colaborar com a Diocese na sua miss\u00e3o de evangeliza\u00e7\u00e3o atrav\u00e9s do Minist\u00e9rio da Educa\u00e7\u00e3o (Escolas da Ag\u00eancia Cat\u00f3lica), particularmente a Escola Secund\u00e1ria Sagrado Cora\u00e7\u00e3o, a Hagita e o Centro Pastoral de S. Paulo.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/1inline.jpg\" alt=\"\" class=\"wp-image-70307\" \/><figcaption><em>Programa de alimenta\u00e7\u00e3o de crian\u00e7as<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>Dois anos de servi\u00e7o em ambas as institui\u00e7\u00f5es, as Irm\u00e3s tamb\u00e9m estabeleceram rela\u00e7\u00f5es com fam\u00edlias que vivem em m\u00e1s condi\u00e7\u00f5es nas aldeias vizinhas. A Comunidade das FC experimentou a generosidade destas fam\u00edlias, pois costumavam trazer produtos de jardim em troca de arroz e peixe. Nas festas da Comunidade, as Irm\u00e3s ofereciam alimenta\u00e7\u00e3o suplementar para crian\u00e7as.<\/p>\n\n\n\n<p>No entanto, observou-se que durante as esta\u00e7\u00f5es chuvosas, os membros da fam\u00edlia n\u00e3o podem cultivar a terra e, para terem algo em cima da mesa, recorrem ao pedido de alimentos, especialmente arroz. Isto tornou-se um padr\u00e3o que foi exacerbado durante o encerramento da COVID 19.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/2inline-1024x446-1.jpg\" alt=\"\" class=\"wp-image-70308\" \/><figcaption><em>Visita a Domic\u00edlio&nbsp;<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>Como alternativa ao sistema de reparti\u00e7\u00e3o de ajuda aos necessitados, a Comunidade decidiu utilizar um m\u00e9todo mais sustent\u00e1vel: APRENDER-TRABALHAR. O fornecimento semanal de alimentos \u00e9 fornecido como incentivo para as pessoas, especialmente as m\u00e3es, se reunirem para estudar, aprender algumas compet\u00eancias e fazer algum trabalho em comum.&nbsp; A finalidade para este desenvolvimento \u00e9 a evangeliza\u00e7\u00e3o integral. O Projeto come\u00e7ou com 25 fam\u00edlias que vivem na pobreza, tendo cinco filhos e que s\u00e3o agricultores subsistentes. As atividades incluem forma\u00e7\u00e3o espiritual, forma\u00e7\u00e3o humana, educa\u00e7\u00e3o na f\u00e9, e servi\u00e7o (forma\u00e7\u00e3o para uma paternidade respons\u00e1vel, cuidado da nossa casa Comum, campanha contra a viol\u00eancia dom\u00e9stica e pol\u00edtica de prote\u00e7\u00e3o infantil).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/3inline.jpg\" alt=\"\" class=\"wp-image-70309\" \/><figcaption><em>M\u00e3es a fazer trabalho comum<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p>Em 2022, o terceiro ano de implementa\u00e7\u00e3o e colhendo os frutos vis\u00edveis do Projeto, a Comunidade de Irm\u00e3s est\u00e1 grata a Deus por esta oportunidade de ouro de O servir nas nossas irm\u00e3s e irm\u00e3os em PNG. A gratid\u00e3o tamb\u00e9m vai para ag\u00eancias estrangeiras como o Projeto de servi\u00e7o Internacional (IPS) do Projeto Filhas da Caridade e BVM Hunger Fund Project das Irm\u00e3s da Caridade da Sant\u00edssima Virgem Maria.<\/p>\n\n\n\n<p>Os benefici\u00e1rios dizem que o APRENDER-TRABALHAR ajudou as suas fam\u00edlias de muitas maneiras, pois aprenderam mais sobre a f\u00e9 cat\u00f3lica e o significado daquilo em que acreditam e por isso s\u00e3o encorajados a testemunhar esta f\u00e9. Uma m\u00e3e est\u00e1 agora a oferecer frutos como papaia madura, banana \u00e0s Irm\u00e3s sempre que vai vender frutos no mercado em gratid\u00e3o pelas muitas b\u00ean\u00e7\u00e3os recebidas pela sua fam\u00edlia. Vangie, uma benefici\u00e1ria, expressou a sua gratid\u00e3o atrav\u00e9s destas palavras: \"Obrigada por este trabalho de aprendizagem onde continuamos a crescer nos aspetos espirituais, econ\u00f3micos e sociais das nossas vidas; recebemos bens materiais, rez\u00e1mos em conjunto, e relacion\u00e1mo-nos bem com outros nas poucas horas de servi\u00e7os que prestamos. Tornei-me mais grata a Deus pelas Suas b\u00ean\u00e7\u00e3os na vida. Deus aben\u00e7oa-nos a todos\".<\/p>\n\n\n\n<p><em>Ir. Roberta SIMBAJON, FC<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/PNG-Photo-4-Kopia.jpg\" alt=\"\" class=\"wp-image-70306\" \/><figcaption><em>Encontro da P\u00e1scoa&nbsp;<\/em><\/figcaption><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":16752,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"categories":[763],"tags":[],"class_list":["post-25289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-santa-luisa-asia-pt-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projecto &quot;Aprender-Trabalhar&quot; - Filles de la Charit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projecto &quot;Aprender-Trabalhar&quot; - Filles de la Charit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/\" \/>\n<meta property=\"og:site_name\" content=\"Filles de la Charit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-30T20:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T11:28:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/PNG-Photo-4-Kopia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1025\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/projecto-aprender-trabalhar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/projecto-aprender-trabalhar\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#\\\/schema\\\/person\\\/427567b2eccfc2dd7d206da186a1f438\"},\"headline\":\"Projecto &#8220;Aprender-Trabalhar&#8221;\",\"datePublished\":\"2022-04-30T20:00:00+00:00\",\"dateModified\":\"2026-05-11T11:28:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/projecto-aprender-trabalhar\\\/\"},\"wordCount\":572,\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/projecto-aprender-trabalhar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/PNG-Photo-4-Kopia.jpg\",\"articleSection\":[\"Santa Lu\u00edsa - \u00c1sia\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/projecto-aprender-trabalhar\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/projecto-aprender-trabalhar\\\/\",\"name\":\"Projecto \\\"Aprender-Trabalhar\\\" - Filles de la Charit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/projecto-aprender-trabalhar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/projecto-aprender-trabalhar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/PNG-Photo-4-Kopia.jpg\",\"datePublished\":\"2022-04-30T20:00:00+00:00\",\"dateModified\":\"2026-05-11T11:28:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/projecto-aprender-trabalhar\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/projecto-aprender-trabalhar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/projecto-aprender-trabalhar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/PNG-Photo-4-Kopia.jpg\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/PNG-Photo-4-Kopia.jpg\",\"width\":1025,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/projecto-aprender-trabalhar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Indonesia\",\"item\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/category\\\/indonesia-pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projecto \u00abAprender-Trabalhar\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/\",\"name\":\"Hijas de la Caridad\",\"description\":\"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies\",\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#organization\",\"name\":\"Hijas de la Caridad\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"width\":1417,\"height\":1417,\"caption\":\"Hijas de la Caridad\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#\\\/schema\\\/person\\\/427567b2eccfc2dd7d206da186a1f438\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/filles-de-la-charite.org\"],\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/author\\\/caridad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projecto \"Aprender-Trabalhar\" - Filles de la Charit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/","og_locale":"pt_PT","og_type":"article","og_title":"Projecto \"Aprender-Trabalhar\" - Filles de la Charit\u00e9","og_url":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/","og_site_name":"Filles de la Charit\u00e9","article_published_time":"2022-04-30T20:00:00+00:00","article_modified_time":"2026-05-11T11:28:01+00:00","og_image":[{"width":1025,"height":768,"url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/PNG-Photo-4-Kopia.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/#article","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/"},"author":{"name":"admin","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#\/schema\/person\/427567b2eccfc2dd7d206da186a1f438"},"headline":"Projecto &#8220;Aprender-Trabalhar&#8221;","datePublished":"2022-04-30T20:00:00+00:00","dateModified":"2026-05-11T11:28:01+00:00","mainEntityOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/"},"wordCount":572,"publisher":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#organization"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/PNG-Photo-4-Kopia.jpg","articleSection":["Santa Lu\u00edsa - \u00c1sia"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/","url":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/","name":"Projecto \"Aprender-Trabalhar\" - Filles de la Charit\u00e9","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/#primaryimage"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/PNG-Photo-4-Kopia.jpg","datePublished":"2022-04-30T20:00:00+00:00","dateModified":"2026-05-11T11:28:01+00:00","breadcrumb":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/#primaryimage","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/PNG-Photo-4-Kopia.jpg","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/06\/PNG-Photo-4-Kopia.jpg","width":1025,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/projecto-aprender-trabalhar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Indonesia","item":"https:\/\/filles-de-la-charite.org\/pt-pt\/category\/indonesia-pt-pt\/"},{"@type":"ListItem","position":2,"name":"Projecto \u00abAprender-Trabalhar\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#website","url":"https:\/\/filles-de-la-charite.org\/pt-pt\/","name":"Hijas de la Caridad","description":"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies","publisher":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filles-de-la-charite.org\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#organization","name":"Hijas de la Caridad","url":"https:\/\/filles-de-la-charite.org\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","width":1417,"height":1417,"caption":"Hijas de la Caridad"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#\/schema\/person\/427567b2eccfc2dd7d206da186a1f438","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/948b492cce32b586ac2db0eaa926ee87024f7afe218d73b397ea5ddfc5f43ea1?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/filles-de-la-charite.org"],"url":"https:\/\/filles-de-la-charite.org\/pt-pt\/author\/caridad\/"}]}},"_links":{"self":[{"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/posts\/25289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=25289"}],"version-history":[{"count":2,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/posts\/25289\/revisions"}],"predecessor-version":[{"id":50638,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/posts\/25289\/revisions\/50638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/media\/16752"}],"wp:attachment":[{"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=25289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=25289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=25289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}