{"id":41522,"date":"2025-02-03T20:31:16","date_gmt":"2025-02-03T19:31:16","guid":{"rendered":"https:\/\/filles-de-la-charite.org\/?p=41522"},"modified":"2026-05-11T13:44:30","modified_gmt":"2026-05-11T11:44:30","slug":"carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion","status":"publish","type":"post","link":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/","title":{"rendered":"Carta do Papa Francisco ao Padre Toma\u017e Mavri\u010d, Superior Geral da Congrega\u00e7\u00e3o da Miss\u00e3o celebrando o IV centen\u00e1rio da sua funda\u00e7\u00e3o."},"content":{"rendered":"\n<p>A 17 de abril de 1625, nasceu a pequena Companhia da Congrega\u00e7\u00e3o da Miss\u00e3o de S\u00e3o Vicente de Paulo. Neste ano jubilar em que a Congrega\u00e7\u00e3o da Miss\u00e3o celebra o IV centen\u00e1rio da sua funda\u00e7\u00e3o, o Papa Francisco dirigiu uma bela mensagem ao nosso Superior Geral Padre Thomas Mavric, a todos os confrades do mundo inteiro e a toda a Fam\u00edlia Vicentina.<\/p>\n\n\n\n<p>A carta do Santo Padre \u00e9 um encorajamento a viver este anivers\u00e1rio com alegria, para que seja para todos n\u00f3s um compromisso de aprofundar a nossa espiritualidade e renovar a nossa fidelidade ao carisma vicentino, que tem o seu fundamento no exemplo de Cristo evangelizador e servidor dos pobres.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file aligncenter\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/02\/Infografico-Fagner-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorpora\u00e7\u00e3o de Infogr\u00e1fico Fagner (1).\"><\/object><a id=\"wp-block-file--media-ba642ad8-bf94-4326-8e93-c19c6f58539a\" href=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/02\/Infografico-Fagner-1.pdf\">Infogr\u00e1fico Fagner (1)<\/a><a href=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/02\/Infografico-Fagner-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-ba642ad8-bf94-4326-8e93-c19c6f58539a\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":41490,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[845],"tags":[],"class_list":["post-41522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional-pt-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carta do Papa Francisco ao Padre Toma\u017e Mavri\u010d, Superior Geral da Congrega\u00e7\u00e3o da Miss\u00e3o celebrando o IV centen\u00e1rio da sua funda\u00e7\u00e3o. - Filles de la Charit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta do Papa Francisco ao Padre Toma\u017e Mavri\u010d, Superior Geral da Congrega\u00e7\u00e3o da Miss\u00e3o celebrando o IV centen\u00e1rio da sua funda\u00e7\u00e3o. - Filles de la Charit\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Filles de la Charit\u00e9\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-03T19:31:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T11:44:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/02\/Lettera-di-Papa-Francesco-A-P.-Tomaz-Mavric-Superiore-Generale-della-Congregazione-della-Missione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SOR MARTA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SOR MARTA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\\\/\"},\"author\":{\"name\":\"SOR MARTA\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#\\\/schema\\\/person\\\/0c922b6ca71280639858d297b3a7209f\"},\"headline\":\"Carta do Papa Francisco ao Padre Toma\u017e Mavri\u010d, Superior Geral da Congrega\u00e7\u00e3o da Miss\u00e3o celebrando o IV centen\u00e1rio da sua funda\u00e7\u00e3o.\",\"datePublished\":\"2025-02-03T19:31:16+00:00\",\"dateModified\":\"2026-05-11T11:44:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\\\/\"},\"wordCount\":147,\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Lettera-di-Papa-Francesco-A-P.-Tomaz-Mavric-Superiore-Generale-della-Congregazione-della-Missione.jpg\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\\\/\",\"name\":\"Carta do Papa Francisco ao Padre Toma\u017e Mavri\u010d, Superior Geral da Congrega\u00e7\u00e3o da Miss\u00e3o celebrando o IV centen\u00e1rio da sua funda\u00e7\u00e3o. - Filles de la Charit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Lettera-di-Papa-Francesco-A-P.-Tomaz-Mavric-Superiore-Generale-della-Congregazione-della-Missione.jpg\",\"datePublished\":\"2025-02-03T19:31:16+00:00\",\"dateModified\":\"2026-05-11T11:44:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Lettera-di-Papa-Francesco-A-P.-Tomaz-Mavric-Superiore-Generale-della-Congregazione-della-Missione.jpg\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Lettera-di-Papa-Francesco-A-P.-Tomaz-Mavric-Superiore-Generale-della-Congregazione-della-Missione.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Internacional\",\"item\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/category\\\/internacional-pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta do Papa Francisco ao Padre Toma\u017e Mavri\u010d, Superior Geral da Congrega\u00e7\u00e3o da Miss\u00e3o celebrando o IV centen\u00e1rio da sua funda\u00e7\u00e3o.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/\",\"name\":\"Hijas de la Caridad\",\"description\":\"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies\",\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#organization\",\"name\":\"Hijas de la Caridad\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"width\":1417,\"height\":1417,\"caption\":\"Hijas de la Caridad\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#\\\/schema\\\/person\\\/0c922b6ca71280639858d297b3a7209f\",\"name\":\"SOR MARTA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g\",\"caption\":\"SOR MARTA\"},\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/author\\\/martaemn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta do Papa Francisco ao Padre Toma\u017e Mavri\u010d, Superior Geral da Congrega\u00e7\u00e3o da Miss\u00e3o celebrando o IV centen\u00e1rio da sua funda\u00e7\u00e3o. - Filles de la Charit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/","og_locale":"pt_PT","og_type":"article","og_title":"Carta do Papa Francisco ao Padre Toma\u017e Mavri\u010d, Superior Geral da Congrega\u00e7\u00e3o da Miss\u00e3o celebrando o IV centen\u00e1rio da sua funda\u00e7\u00e3o. - Filles de la Charit\u00e9","og_url":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/","og_site_name":"Filles de la Charit\u00e9","article_published_time":"2025-02-03T19:31:16+00:00","article_modified_time":"2026-05-11T11:44:30+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/02\/Lettera-di-Papa-Francesco-A-P.-Tomaz-Mavric-Superiore-Generale-della-Congregazione-della-Missione.jpg","type":"image\/jpeg"}],"author":"SOR MARTA","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"SOR MARTA","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/#article","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/"},"author":{"name":"SOR MARTA","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#\/schema\/person\/0c922b6ca71280639858d297b3a7209f"},"headline":"Carta do Papa Francisco ao Padre Toma\u017e Mavri\u010d, Superior Geral da Congrega\u00e7\u00e3o da Miss\u00e3o celebrando o IV centen\u00e1rio da sua funda\u00e7\u00e3o.","datePublished":"2025-02-03T19:31:16+00:00","dateModified":"2026-05-11T11:44:30+00:00","mainEntityOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/"},"wordCount":147,"publisher":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#organization"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/02\/Lettera-di-Papa-Francesco-A-P.-Tomaz-Mavric-Superiore-Generale-della-Congregazione-della-Missione.jpg","articleSection":["Internacional"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/","url":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/","name":"Carta do Papa Francisco ao Padre Toma\u017e Mavri\u010d, Superior Geral da Congrega\u00e7\u00e3o da Miss\u00e3o celebrando o IV centen\u00e1rio da sua funda\u00e7\u00e3o. - Filles de la Charit\u00e9","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/#primaryimage"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/02\/Lettera-di-Papa-Francesco-A-P.-Tomaz-Mavric-Superiore-Generale-della-Congregazione-della-Missione.jpg","datePublished":"2025-02-03T19:31:16+00:00","dateModified":"2026-05-11T11:44:30+00:00","breadcrumb":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/#primaryimage","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/02\/Lettera-di-Papa-Francesco-A-P.-Tomaz-Mavric-Superiore-Generale-della-Congregazione-della-Missione.jpg","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2025\/02\/Lettera-di-Papa-Francesco-A-P.-Tomaz-Mavric-Superiore-Generale-della-Congregazione-della-Missione.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/carta-del-papa-francisco-al-p-tomaz-mavric-superior-general-de-la-congregacion-de-la-mision-con-motivo-del-iv-centenario-de-su-fundacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Internacional","item":"https:\/\/filles-de-la-charite.org\/pt-pt\/category\/internacional-pt-pt\/"},{"@type":"ListItem","position":2,"name":"Carta do Papa Francisco ao Padre Toma\u017e Mavri\u010d, Superior Geral da Congrega\u00e7\u00e3o da Miss\u00e3o celebrando o IV centen\u00e1rio da sua funda\u00e7\u00e3o."}]},{"@type":"WebSite","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#website","url":"https:\/\/filles-de-la-charite.org\/pt-pt\/","name":"Hijas de la Caridad","description":"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies","publisher":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filles-de-la-charite.org\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#organization","name":"Hijas de la Caridad","url":"https:\/\/filles-de-la-charite.org\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","width":1417,"height":1417,"caption":"Hijas de la Caridad"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#\/schema\/person\/0c922b6ca71280639858d297b3a7209f","name":"SOR MARTA","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2c45b0fd6bf2d3e2670ab3d112257c24ac80fa960360bba1bdc0676485d1d09?s=96&d=mm&r=g","caption":"SOR MARTA"},"url":"https:\/\/filles-de-la-charite.org\/pt-pt\/author\/martaemn\/"}]}},"_links":{"self":[{"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/posts\/41522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=41522"}],"version-history":[{"count":3,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/posts\/41522\/revisions"}],"predecessor-version":[{"id":51134,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/posts\/41522\/revisions\/51134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/media\/41490"}],"wp:attachment":[{"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=41522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=41522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=41522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}