{"id":30485,"date":"2023-10-30T09:37:46","date_gmt":"2023-10-30T08:37:46","guid":{"rendered":"https:\/\/hijascaridad.sjdigitaldemo.ovh\/service\/criancas\/"},"modified":"2024-03-01T10:39:34","modified_gmt":"2024-03-01T09:39:34","slug":"criancas","status":"publish","type":"service","link":"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/","title":{"rendered":"As crian\u00e7as"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Para Santa Lu\u00edsa de Marillac, nossa Fundadora, o cuidado das crian\u00e7as era um dos servi\u00e7os mais importantes das Filhas da Caridade.  <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">A sua experi\u00eancia pessoal, ensinou-lhe o quanto a presen\u00e7a de pessoas am\u00e1veis e bondosas s\u00e3o importantes na vida das crian\u00e7as, especialmente daquelas que s\u00e3o \u00f3rf\u00e3s, abandonadas ou v\u00edtimas da separa\u00e7\u00e3o dos pais.<br>As crian\u00e7as precisam de aten\u00e7\u00e3o, cuidados e orienta\u00e7\u00e3o para crescerem saud\u00e1veis e prosperarem. De fato, a falta de afeto na inf\u00e2ncia tem consequ\u00eancias para toda a vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Em muitas regi\u00f5es, as crian\u00e7as j\u00e1 n\u00e3o t\u00eam direito a uma inf\u00e2ncia. Sem fam\u00edlia e muito pobres, precisam trabalhar e s\u00e3o frequentemente exploradas por aqueles que deviam respeit\u00e1-las e ajud\u00e1-las.<br>As crian\u00e7as, por vezes, ainda pequenas, tornam-se agressivas e consomem drogas porque, na maior parte do tempo, n\u00e3o t\u00eam acesso a outras oportunidades. Por esta raz\u00e3o, e porque s\u00e3o os membros mais fracos da sociedade, devemos dar-lhes prioridade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Contribu\u00edmos para o bem-estar das crian\u00e7as de diferentes maneiras:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>na educa\u00e7\u00e3o infantil e fundamental I<\/li>\n\n\n\n<li>atrav\u00e9s de lares para crian\u00e7as, da assist\u00eancia para ado\u00e7\u00e3o e da procura de fam\u00edlias de acolhimento.<\/li>\n\n\n\n<li>atrav\u00e9s da luta contra a desnutri\u00e7\u00e3o<\/li>\n\n\n\n<li>atrav\u00e9s de programas de apoio aos pais e familiares<\/li>\n<\/ul>\n","protected":false},"featured_media":1929,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"class_list":["post-30485","service","type-service","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As crian\u00e7as - Filles de la Charit\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As crian\u00e7as - Filles de la Charit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Para Santa Lu\u00edsa de Marillac, nossa Fundadora, o cuidado das crian\u00e7as era um dos servi\u00e7os mais importantes das Filhas da Caridade. A sua experi\u00eancia pessoal, ensinou-lhe o quanto a presen\u00e7a de pessoas am\u00e1veis e bondosas s\u00e3o importantes na vida das crian\u00e7as, especialmente daquelas que s\u00e3o \u00f3rf\u00e3s, abandonadas ou v\u00edtimas da separa\u00e7\u00e3o dos pais.As crian\u00e7as precisam [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/\" \/>\n<meta property=\"og:site_name\" content=\"Filles de la Charit\u00e9\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-01T09:39:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/04\/Ninos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/service\\\/criancas\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/service\\\/criancas\\\/\",\"name\":\"As crian\u00e7as - Filles de la Charit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/service\\\/criancas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/service\\\/criancas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Ninos.jpg\",\"datePublished\":\"2023-10-30T08:37:46+00:00\",\"dateModified\":\"2024-03-01T09:39:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/service\\\/criancas\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/service\\\/criancas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/service\\\/criancas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Ninos.jpg\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Ninos.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/service\\\/criancas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Services\",\"item\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/service\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As crian\u00e7as\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/\",\"name\":\"Hijas de la Caridad\",\"description\":\"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies\",\"publisher\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#organization\",\"name\":\"Hijas de la Caridad\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"contentUrl\":\"https:\\\/\\\/filles-de-la-charite.org\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/isotipo-Hijas-de-la-Caridad.png\",\"width\":1417,\"height\":1417,\"caption\":\"Hijas de la Caridad\"},\"image\":{\"@id\":\"https:\\\/\\\/filles-de-la-charite.org\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As crian\u00e7as - Filles de la Charit\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/","og_locale":"pt_PT","og_type":"article","og_title":"As crian\u00e7as - Filles de la Charit\u00e9","og_description":"Para Santa Lu\u00edsa de Marillac, nossa Fundadora, o cuidado das crian\u00e7as era um dos servi\u00e7os mais importantes das Filhas da Caridade. A sua experi\u00eancia pessoal, ensinou-lhe o quanto a presen\u00e7a de pessoas am\u00e1veis e bondosas s\u00e3o importantes na vida das crian\u00e7as, especialmente daquelas que s\u00e3o \u00f3rf\u00e3s, abandonadas ou v\u00edtimas da separa\u00e7\u00e3o dos pais.As crian\u00e7as precisam [&hellip;]","og_url":"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/","og_site_name":"Filles de la Charit\u00e9","article_modified_time":"2024-03-01T09:39:34+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/04\/Ninos.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/","url":"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/","name":"As crian\u00e7as - Filles de la Charit\u00e9","isPartOf":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/#primaryimage"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/#primaryimage"},"thumbnailUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/04\/Ninos.jpg","datePublished":"2023-10-30T08:37:46+00:00","dateModified":"2024-03-01T09:39:34+00:00","breadcrumb":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/#primaryimage","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/04\/Ninos.jpg","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/04\/Ninos.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/criancas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Services","item":"https:\/\/filles-de-la-charite.org\/pt-pt\/service\/"},{"@type":"ListItem","position":2,"name":"As crian\u00e7as"}]},{"@type":"WebSite","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#website","url":"https:\/\/filles-de-la-charite.org\/pt-pt\/","name":"Hijas de la Caridad","description":"L\u2019amour de J\u00e9sus nous presse \u00e0 prendre soin des personnes les plus d\u00e9munies","publisher":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filles-de-la-charite.org\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#organization","name":"Hijas de la Caridad","url":"https:\/\/filles-de-la-charite.org\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","contentUrl":"https:\/\/filles-de-la-charite.org\/wp-content\/uploads\/2023\/03\/isotipo-Hijas-de-la-Caridad.png","width":1417,"height":1417,"caption":"Hijas de la Caridad"},"image":{"@id":"https:\/\/filles-de-la-charite.org\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/service\/30485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/service"}],"about":[{"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/types\/service"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/media\/1929"}],"wp:attachment":[{"href":"https:\/\/filles-de-la-charite.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=30485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}